{"id":14550,"date":"2025-10-01T13:11:06","date_gmt":"2025-10-01T11:11:06","guid":{"rendered":"https:\/\/terranatur.es\/web\/?page_id=14550"},"modified":"2026-03-11T08:33:49","modified_gmt":"2026-03-11T07:33:49","slug":"dunas-raid-marruecos","status":"publish","type":"page","link":"https:\/\/terranatur.es\/web\/dunas-raid-marruecos\/","title":{"rendered":"DUNAS RAID IX &#8211; MARRUECOS"},"content":{"rendered":"<h1>\n<p>DUNAS RAID IX MARRUECOS.<\/p>\n<p>SEMANA SANTA 2026<\/p>\n<\/h1>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-32.jpg\" alt=\"Descanso en el Shagro\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-57.jpg\" alt=\"La Momia. Gara de Medouar\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/dromedarios-erg.jpg\" alt=\"Dromedarios por el Erg Chebbi. Marruecos\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-terranatur-1600-05.jpg\" alt=\"Atravesando el Shagro\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-67.jpg\" alt=\"Tener\u00edas de Fez\"><\/p>\n<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/LOGO-DUNAS-RAID-2025-IX-1.png\" alt=\"Logo tipo Dunas Raid IX. Marruecos 4x4 con Terranatur\"><br \/>\n<img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/palmeras-verticas.jpg\" alt=\"palmeral\"><\/p>\n<div>\n<h2>Dos desiertos, un destino: Descubre Marruecos en 4&#215;4<\/h2>\n<div>\n<p><strong>Semana Santa:<\/strong> (26) 27 marzo &#8211; (5) 6 de abril de 2026<\/p>\n<p>Riads, Kasbahs y Lodges con encanto y m\u00e1xima calidad hotelera en su zona.<\/p>\n<p>Gu\u00edas: Jaime Roset y Paloma Mill\u00e1n .<\/p>\n<h4>\u00a1ALGUNAS PLAZAS LIBRES DE \u00daLTIMA HORA!<\/h4>\n<h5>Viajeros hasta la fecha:<\/h5>\n<ol>\n<li><strong>Claudio y Br\u00edgida.<\/strong> Mitsubishi Montero.<span class=\"Apple-tab-span\"> <\/span>Ciudad Real.<\/li>\n<li><strong>Jos\u00e9 Ignacio y Pilar<\/strong>.<span class=\"Apple-tab-span\"> <\/span>Land Rover Defender.<span class=\"Apple-tab-span\"> <\/span>Ciudad Real.<\/li>\n<li><strong>Pere y Francesc. <\/strong>(Blauet)\u00a0Toyota Land Cruiser 95. Rub\u00ed.<\/li>\n<li><strong>Miguel, Ilenia y Mateo.<\/strong> Nissan Terrano II. Madrid.<\/li>\n<li><strong>Paco, Raquel y Guille<\/strong>\u00a0(17) . Mitsubishi Montero. Madrid<\/li>\n<li><strong>Pepe, Irene y Ana<\/strong> (Padawan). Land Rover Discovery 4. Valdepe\u00f1as.<\/li>\n<li><strong>Mar\u00eda, Fernando, Gonzalo y Albert<\/strong>o (Padawan). Land Rover Discovery 4. Valdepe\u00f1as.<\/li>\n<li><strong>Roberto y Monica. <\/strong>Isuzu Dmax Extrem. Asturias.<\/li>\n<li><strong>Jorge, Sara y Leo (16)<\/strong>. Toyota Land Cruiser. Cantabria.<\/li>\n<li><strong>Carola, Jos\u00e9 Mar\u00eda y Dani (10).<\/strong> Land Rover Defender. Madrid.<\/li>\n<li><strong>Mirian, Ivan, Nico (13), Max (9)<\/strong>. (Beskar) Jeep Wrangler. Barcelona<\/li>\n<li>&#8230;<\/li>\n<li><strong>Goyo (Gu\u00eda-conductor).<\/strong> Kia Sorento. Toledo.<\/li>\n<li><strong>Jaime y Paloma (Gu\u00edas).<\/strong> Toyota Hilux. Madrid.<\/li>\n<\/ol>\n<ol><\/ol>\n<ol><\/ol>\n<ol><\/ol>\n<p>\u00a1<strong>LAS DUNAS<\/strong>!&#8230; Cuando las descubres, algo cambia en ti. Dicen que amamos lo que no tenemos. Las dunas son una provocaci\u00f3n a la aventura. Quiz\u00e1 son uno de los paisajes m\u00e1s bellos y sugestivos que puedas encontrar en el mundo. La sensaci\u00f3n de caminar o surfear en tu 4&#215;4 sobre ellas, no tiene comparaci\u00f3n alguna.<\/p>\n<p>Por el camino, visitaremos lugares sorprendentes mientras nos imbuimos en la cultura bereber y \u00e1rabe. \u00bfTe gusta la fotograf\u00eda o grabar v\u00eddeos? Has llegado al lugar correcto: aqu\u00ed podr\u00e1s disfrutar tu afici\u00f3n a tope.<\/p>\n<p>Adem\u00e1s, si vienes con familia, para tus hijos ser\u00e1 una ocasi\u00f3n \u00fanica. Para ti, tambi\u00e9n.<\/p>\n<p>Este viaje es como un regreso al pasado y los paisajes te dejar\u00e1n encantado.<\/p>\n<h5>FORMAS DE VIAJAR:<\/h5>\n<ul>\n<li>EN TU PROPIO 4X4\u00a0<\/li>\n<li>DE PASAJEROS EN 4&#215;4 CON UN GU\u00cdA CONDUCTOR\u00a0<\/li>\n<li>ALQUILANDO ALL\u00cd UN 4X4<\/li>\n<\/ul>\n<ul>\n<li>N\u00daMERO DE 4X4 PARTICIPANTES LIMITADO.<\/li>\n<li>POR AGILIDAD, SE FORMAR\u00c1N SUBGRUPOS DE 7-8 COCHES.<\/li>\n<\/ul>\n<h5>RESERVA AHORA tu viaje CON TODA CONFIANZA.<\/h5>\n<p>Haremos rutas 4&#215;4 y pistas especiales por paisajes que te dejar\u00e1n sin aliento\u2026ven a la aventura sahariana con nosotros.<strong>\u00a0<\/strong><strong>Incluye Asilah, Catedral de Rocas de Imsfrane, Garganta de Asiff Melloul, Cascadas de Ouzoud, Valle de Ourika (alto Atlas), Valle de Ounila, Ait Ben Haddou, Ouarzazate, Gargantas del Dades y Todra, Tinehir, Ciudad Perdida, Erg Ouzina, Erg Chebbi, <\/strong><strong>Bosque de Cedros, Fez, Chefchaouen, <\/strong><strong>cursillo de conducci\u00f3n en dunas y mucho m\u00e1s.\u00a0<\/strong><\/p>\n<p><b>El itinerario definitivo est\u00e1 sujeto a confirmaci\u00f3n.<\/b><\/p>\n<p>Nos gusta contactar con la poblaci\u00f3n local. Sentir\u00e1s lo acogedores que son nuestros amigos bereberes, \u00e1rabes y n\u00f3madas. \u00a0<\/p>\n<p>NOTA IMPORTANTE: <strong>SOLO 4X4 CON REDUCTORA,\u00a0 RUEDAS MIXTAS M\u00cdNIMO 50-50, Y LLANTAS DE DE 18&#8242; O MENOS.<\/strong><\/p>\n<p>Naturaleza: 4\/5\u00a0\u00a0 Gastronom\u00eda: 4\/5\u00a0\u00a0 Ni\u00f1os: \u00a1ok!<\/p>\n<div class=\"uk-child-width-1-2 uk-grid-large\" uk-grid=\"\">\n<div class=\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\" uk-grid=\"\">\n<div style=\"max-width: 80px;\"><img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/trans-alps-about-icon-01.svg\" alt=\"\" uk-svg=\"\" \/><\/div>\n<div class=\"uk-flex uk-flex-center uk-flex-middle\" style=\"max-width: 80px;\">\n<div class=\"uk-h6\">700 km offroad aprox<\/div>\n<\/div>\n<\/div>\n<div class=\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\" uk-grid=\"\">\n<div style=\"max-width: 80px;\"><img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/trans-alps-about-icon-02.svg\" alt=\"\" uk-svg=\"\" \/><\/div>\n<div class=\"uk-flex uk-flex-center uk-flex-middle\" style=\"max-width: 80px;\">\n<div class=\"uk-h6\">10 d\u00edas<\/div>\n<\/div>\n<\/div>\n<div class=\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\" uk-grid=\"\">\n<div style=\"max-width: 80px;\"><img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/trans-alps-about-icon-03.svg\" alt=\"\" uk-svg=\"\" \/><\/div>\n<div class=\"uk-flex uk-flex-center uk-flex-middle\" style=\"max-width: 80px;\">\n<div class=\"uk-h6\">Dunas, Hammadas, Atlas<\/div>\n<\/div>\n<\/div>\n<div class=\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\" uk-grid=\"\">\n<div style=\"max-width: 80px;\"><img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/trans-alps-about-icon-04.svg\" alt=\"\" uk-svg=\"\" \/><\/div>\n<div class=\"uk-flex uk-flex-center uk-flex-middle\" style=\"max-width: 80px;\">\n<div class=\"uk-h6\">Dificultad: 3-4\/5 seg\u00fan etapa<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><p>\n        <a href=\"\/web\/comprar\/reserva-dunas-raid-marruecos\/\">RESERVAR AHORA<\/a>\n    <\/p>\n<\/p>\n<h1>PLAN DE VIAJE<\/h1>\n<div>\n<p>Aqu\u00ed tienes el itinerario y el programa de viaje con tu propio 4&#215;4, acompa\u00f1ado siempre de gu\u00edas expertos e instructores 4&#215;4. Dentro de los viajes de aventura a Marruecos, es sin duda uno de los m\u00e1s completos en 11 etapas.<\/p>\n<\/div>\n<p><img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/MAPA-MARRUECOS-ITINERARIO-ETAPAS.jpg\" alt=\"itinerario Marruecos Semana Santa 2026\"><\/p>\n<h1>ITINERARIO VIAJE DUNAS RAID IX<\/h1>\n<div>\n<p>Todos los a\u00f1os hacemos modificaciones para <strong>mejorar<\/strong> y hacer m\u00e1s interesante el recorrido, ya que <strong>nuestros viajeros\u00a0 frecuentemente repiten<\/strong> con nosotros edici\u00f3n tras edici\u00f3n; por eso, hasta un mes antes de la salida, <strong>este recorrido puede verse alterado<\/strong>.\u00a0<\/p>\n<\/div>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/asilah-marruecos-terranatur.jpg\" alt=\"Ashila Marruecos\"><\/p>\n<h3>D\u00cdA 1 (27 DE MARZO 2026). ALGECIRAS &#8211; PASO DEL ESTRECHO &#8211; MEKNESS<\/h3>\n<div>\n<p>Cruzamos el estrecho en el primer ferry rumbo a Marruecos. Salimos de <strong>Algeciras<\/strong> para llegar a <strong>Tanger Med<\/strong>.\u00a0<\/p>\n<p>Desde ah\u00ed por carretera hasta <strong>Asilah<\/strong>, la \u00abperla de Marruecos\u00bb peque\u00f1a y preciosa poblaci\u00f3n costera donde comeremos.<\/p>\n<p>Ruta por carretera hasta <strong>Mekness<\/strong> comenzando a descubrir este interesante pa\u00eds.\u00a0<\/p>\n<p>Aposentamiento en el hotel, cena y si te apetece: tiempo libre para una <strong>visita nocturna a Mekness<\/strong>.\u00a0<\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/catedras-rocas-imsfrane.jpg\" alt=\"Catedral de Rocas de Imsfrane. Marruecos\"><\/p>\n<h3>DIA 2 (28 MARZO 2026). MEKNESS &#8211; PARQUE NACIONAL DE JENIFRA &#8211; IMILCHIL<\/h3>\n<div>\n<p>Desde <strong>Mekness<\/strong> nos dirigimos al Atlas Medio pasando por el Parque Nacional de <strong>Jenifra<\/strong>.\u00a0<\/p>\n<p>Llegando a las monta\u00f1as, comienza una ruta por visitando <strong>las fuentes del OUM RABIA<\/strong>, y el<strong> Bosque de Cedros<\/strong> haciendo una ruta de monta\u00f1a completamente nueva, que nos llevar\u00e1 hasta el coraz\u00f3n del Atlas en <strong>Imilchil<\/strong>.<\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/cascadas-de-ouzoud.jpg\" alt=\"Cascada de Ouzoud. Marruecos.\"><\/p>\n<h3>D\u00cdA 3 (29 MARZO 2026). IMILCHIL &#8211; CATEDRAL DE ROCAS &#8211; CASCADAS DE OUZOUD<\/h3>\n<div>\n<p>Seguimos de ruta 4&#215;4 hasta dos de las joyas escondidas que m\u00e1s nos gustan: <strong>La Catedral de Rocas de Imsfrane<\/strong> y la Garganta de <strong>Asiff Melloul<\/strong>, una de las m\u00e1s bellas y menos conocidas del pa\u00eds.<\/p>\n<p>Siguiendo por carreteras de monta\u00f1a por el Atlas descubriremos la cascada m\u00e1s alta del norte de \u00c1frica, en las <strong>Cascadas de Ouzoud<\/strong>, una verdadera belleza y rareza geol\u00f3gica.\u00a0<\/p>\n<p>Noche en <strong>Palais du Ouzoud.\u00a0<\/strong><\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-88.jpg\" alt=\"Valle de Ourika 4x4\"><\/p>\n<h3>D\u00cdA 4 (30 MARZO 2026). CASCADAS DE OUZOUD-OURIKA<\/h3>\n<div>\n<p>En esta etapa nos dirigimos al m\u00e1gico <strong>valle de Ourika<\/strong>, uno de nuestros destinos m\u00e1s divertidos y singulares. Por la tarde entraremos desde <strong>Oukamaiden<\/strong> para la conquista del paso en el alto Atlas a m\u00e1s de <strong>3000<\/strong> metros por donde pasa la pista.\u00a0<\/p>\n<p>El objetivo es recorrer la zona hasta<strong> Seti Fatma<\/strong> y cenar ah\u00ed.\u00a0<\/p>\n<p>Noche en un riad cercano.<\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur16.jpg\" alt=\"Palmeral \"><\/p>\n<h3>D\u00cdA 5 (31 MARZO 2026). VALLE DE OURIKA- AIT BEN HADDOU<\/h3>\n<div>\n<p>Nos dirigimos a atravesar el <strong>Alto Atlas<\/strong> por carreteras de monta\u00f1a impresionantes. Cambiamos de vertiente y entramos en el sur de Marruecos, cruzando el puerto del <strong>Tizi&#8217;n Tischka<\/strong>. Visitaremos la Kasbah m\u00e1s famosa: <strong>Ait Ben Haddou<\/strong>, uno de los escenarios m\u00e1s legendarios de pel\u00edculas.\u00a0\u00a0<\/p>\n<p>Noche en la Kasbah aut\u00e9ntica dentro de Ait Ben Haddou.\u00a0<\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur12.jpg\" alt=\"shagro. Antiatlas marroqui\"><\/p>\n<h3>D\u00cdA 6 (1 ABRIL 2026). AIT BEN HADDOU &#8211; DADES &#8211; TODRA<\/h3>\n<div>\n<p>Bonita pista hasta <strong>Ouarzazate<\/strong>, la meca del cine.\u00a0<\/p>\n<p>Posible visita voluntaria a los estudios cinematogr\u00e1ficos.\u00a0<\/p>\n<p>Dedicamos esta jornada para explorar las magn\u00edficas Gargantas del <strong>Todra y del Dades<\/strong>, incluyendo el pueblo de <strong>Tinerhir<\/strong>, con sus ruinas y palmerales inolvidables.<\/p>\n<p>Noche en riad tradicional.<\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur32.jpg\" alt=\"doradas dunas del Erg Ouzina\"><\/p>\n<h3>D\u00cdA 7 (2 ABRIL 2026)  DADES &#8211; JBEL SHAGRO &#8211; DUNAS ERG OUZINA<\/h3>\n<div>\n<p>En este trayecto tenemos el resto de atravesar la tortuosa cordillera volc\u00e1nica del <strong>Shagro<\/strong>, un laberinto de pistas que no os dejar\u00e1 indiferentes.\u00a0<\/p>\n<p>Cruzando las zonas subdes\u00e9rticas llegaremos a la <strong>ciudad perdida,<\/strong> antesala a las <strong>dunas del Erg Ouzina<\/strong>.\u00a0<\/p>\n<p>Por la noche, observaci\u00f3n de estrellas y t\u00e9cnicas b\u00e1sicas de orientaci\u00f3n astron\u00f3mica. Estamos en un <strong>destino Starlight<\/strong> \u00fanico!!!<br \/><strong><\/strong><\/p>\n<p><strong>Alojamiento y cena:<\/strong> Riad Ouzina TGM, Riad Rimal o khaimas bereberes aut\u00e9nticas.<\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/2015-03-marruecos-1426-scaled-2.jpg\" alt=\"Dunas de Merzouga con Terranatur\"><\/p>\n<h3> D\u00cdA 8 (3 ABRIL 2026). ERG OUZINA &#8211; ERG CHEBBI <\/h3>\n<div>\n<p>Nos dirigimos al <strong>Erg Chebbi<\/strong> tras un <strong>cursillo de conducci\u00f3n en dunas<\/strong> en el\u00a0<strong>Erg Ouzina.<\/strong><\/p>\n<p>Descubrimos los secretos del mayor <strong>mar de Dunas de Marruecos.\u00a0<\/strong><\/p>\n<p>Noche en <strong>Kasbah Yasmina<\/strong>.\u00a0<\/p>\n<\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur14.jpg\" alt=\"Desiertos pedregosos\"><\/p>\n<h3>DIA 9 (4 ABRIL 2026). DUNAS DEL ERG CHEBBI &#8211; MIDELT<\/h3>\n<div>\n<p>Disfrutamos del <strong>amanecer<\/strong> en las dunas antes de emprender una bonita etapa hasta <strong>Midelt<\/strong>. Por la ma\u00f1ana aprovecharemos para navegar de nuevo por las dunas.\u00a0<\/p>\n<p>Recorrido por carretera atravesando la <strong>garganta del Fiz<\/strong>.<\/p>\n<p>Noche en el <strong>hotel Taddart de Midelt.<\/strong><\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-terranatur-03.jpg\" alt=\"Puesta de sol en Chefchaouen\"><\/p>\n<h3>D\u00cdA 10 (5 ABRIL 2026). MIDELT &#8211; FEZ &#8211; CHEFCHAOUEN<\/h3>\n<div>\n<p>Salimos de Midelt camino de <strong>Fez<\/strong>, cruzando <strong>bosques de cedros<\/strong>. El objetivo es comer en la medina de Fez y llegar a cenar a <strong>Chefchaouen<\/strong>, la ciudad a\u00f1il.\u00a0<\/p>\n<p>Noche en <strong>Dar Ba Sidi.<\/strong><\/p>\n<p><strong>CONSULTA EMBARCAR ESA MISMA NOCHE SI LO PREFIERES (NO RECOMENDABLE).<\/strong><\/p>\n<\/div>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/ferry-tarifa.jpg\" alt=\"Saliendo hacia Africa\"><\/p>\n<h3>D\u00cdA 11 (6 ABRIL 2026) CHEFCHAOUEN &#8211; TANGER MED &#8211; ALGECIRAS<\/h3>\n<div>\n<p>Salimos desde <strong>Chefchaouen<\/strong>, conocida como la \u00abciudad azul\u00bb, rumbo <strong>Tanger Med<\/strong> pasando por <strong>Tetuan<\/strong>.<\/p>\n<p>Cruce del estrecho al llegar a puerto, destino <strong>Algeciras<\/strong>.\u00a0<\/p>\n<p>Fin de nuestra aventura de momento&#8230; \ud83d\ude09<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/DSC_0386-1536x1020-1.jpg\" alt=\"Por las Hammadas Marroqu\u00edes\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/2017-04-MARRUECOS-2017-2260-1536x1023-1.jpg\" alt=\"Paisaje de Erg Ouzina\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-2014-493-1536x1020-1.jpg\" alt=\"Dromedario en las dunas de Marruecos\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-2016-182-scaled-1.jpg\" alt=\"Por el Atlas Marroqu\u00ed\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/P4161249-2048x1536-1.jpg\" alt=\"Pueblo Gwana en Merzouga\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-terranatur-2150-04.jpg\" alt=\"Por el Shagro con Terranatur\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-terranatur-1600-07.jpg\" alt=\"4x4 en el Saghro\"><\/p>\n<\/li>\n<\/ul>\n<div>Alojamientos con encanto<\/div>\n<h2>kasbahs, riads, Khaimas<\/h2>\n<div>\n<p>En Marruecos elegimos siempre lugares muy especiales, algunos \u00abde las mil y una noches\u00bb, junto con algunos riads que por su localizaci\u00f3n en medio del desierto, suponen una experiencia \u00fanica. Alguna de las noches ser\u00e1 posible dormir en Khaima en pleno desierto.<\/p>\n<\/div>\n<blockquote>\n<p>\u00abVen a que te pique el \u00abbicho africano\u00bb con nosotros. Una vez conozcas Marruecos y sus dunas, necesitar\u00e1s volver a volver&#8230; una y otra vez \u00ab<\/p>\n<footer>\n<p>                <cite>El equipo Terranatur<\/cite><\/p>\n<\/footer>\n<\/blockquote>\n<p><img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-53.jpg\" alt=\"Fiesta en las dunas\"><\/p>\n<h3>PRECIOS VIAJE<\/h3>\n<div>\n<h4><strong>El total del viaje es la suma del precio de cada persona y el veh\u00edculo. (11 d\u00edas\/9-10 noches).<\/strong><\/h4>\n<h4>PRECIO POR PERSONA en 4X4 particular:<\/h4>\n<ul>\n<li>Cada adulto: <strong>1450<\/strong>\u00a0\u20ac<strong> <\/strong>(precio de cada uno de los dos primeros ocupantes, compartiendo habitaci\u00f3n y 4&#215;4).\u00a0<\/li>\n<li>A partir del tercer ocupante en el mismo 4&#215;4 y en la misma habitaci\u00f3n, mayor de 12 a\u00f1os: <strong>1260<\/strong> \u20ac\u00a0<\/li>\n<li>Ni\u00f1o (4-11 a\u00f1os): <strong>998<\/strong> \u20ac<strong><br \/><\/strong><\/li>\n<li>Ni\u00f1o menor de 3 a\u00f1os, consultar.<\/li>\n<li>Adulto solo en su propio 4&#215;4: <strong>2270<\/strong> \u20ac<\/li>\n<li>Un adulto con un menor tienen consideraci\u00f3n como dos adultos.<\/li>\n<li>Consultar extra por habitaci\u00f3n individual si la elige alguno de tus ocupantes.<\/li>\n<li>Consultar alquiler <strong>Toyota Land Cruiser africano<\/strong>.<\/li>\n<\/ul>\n<h4>PRECIO POR VEH\u00cdCULO 4X4 V\u00cdA ALGECIRAS &#8211; TANGER MED &#8211; ALGECIRAS (paso del Estrecho en ferry y gesti\u00f3n pasajes)<\/h4>\n<ul>\n<li>Por veh\u00edculo 4&#215;4 con 1 persona: <strong>385\u00a0\u20ac<\/strong><\/li>\n<li>Por veh\u00edculo 4&#215;4 con 2 personas: <strong>456 \u20ac<\/strong><\/li>\n<li>Por veh\u00edculo 4&#215;4 con 3 personas: <strong>527 \u20ac<\/strong><\/li>\n<li>Por veh\u00edculo 4&#215;4 con 4 personas: <strong>598\u00a0\u20ac<\/strong><\/li>\n<li>Por veh\u00edculo 4&#215;4 con 5 personas: <strong>669 \u20ac<\/strong><\/li>\n<\/ul>\n<p>Si deseas embarcar en TARIFA y llegar a TANGER CIUDAD: tiene un suplemento de + 90 \u20ac por adulto y 50 \u20ac ni\u00f1os menores de 11 a\u00f1os en el total del viaje.<\/p>\n<p><strong>Ejemplo del coste total de un viaje<\/strong> para dos adultos y un joven o adulto mayor de 12 a\u00f1os en el mismo 4&#215;4 propio y compartiendo habitaci\u00f3n: 1450 \u20ac + 1450 \u20ac + 1260 \u20ac + 527 \u20ac = <strong>4687\u00a0\u20ac\u00a0<\/strong><\/p>\n<p>Extra habitaci\u00f3n individual: <strong>+310 \u20ac<br \/><\/strong>Extra cruce del estrecho por Tarifa:<strong> + 90 \u20ac<\/strong> por adulto.\u00a0<\/p>\n<h6>Puedes reservar ahora por 500 \u20ac\u00a0 por coche para asegurar vuestra plaza. Salida garantizada a partir de cuatro coches inscritos un mes antes del inicio del viaje.\u00a0<\/h6>\n<ul><\/ul>\n<h5>INCLUYE:<\/h5>\n<ul>\n<li>Rutas guiadas en peque\u00f1os grupos guiadas por Marruecos.<\/li>\n<li>Rutas 4&#215;4 en 7 de las etapas (zona sur y en el atlas)<\/li>\n<li>Cursillo de conducci\u00f3n en dunas.<\/li>\n<li>Formaci\u00f3n en orientaci\u00f3n mediante dispositivos m\u00f3viles.<\/li>\n<li>9-10 noches en media pensi\u00f3n cena y desayuno (alojamiento en riads, Kasbahs, khaimas u hoteles). Consulta concertar aparte la noche de antes y la \u00faltima.<\/li>\n<li>Ferry Algeciras &#8211; Tanger Med &#8211; Algeciras o Tarifa-Tanger Ville-Tarifa (con suplemento).\u00a0<\/li>\n<li>Seguro de viaje TOP con anulaci\u00f3n de ARAG (<a href=\"https:\/\/terranatur.es\/web\/wp-content\/uploads\/Resumen_TOP_E14_MARZO_2024.pdf\" target=\"_blank\" rel=\"noopener\">resumen<\/a> &#8211; <a href=\"https:\/\/www.i4t.es\/download\/documento?uid=pAJFV6rmoRdvGzQqTylZeqFnImQmMtJM\" target=\"_blank\" rel=\"noopener\">condiciones generales<\/a>)<\/li>\n<li>Tasas tur\u00edsticas locales.<\/li>\n<li>Gu\u00edas espa\u00f1oles y locales de habla hispana. Idioma de prestaci\u00f3n de servicios en Espa\u00f1ol.<\/li>\n<li>Veh\u00edculo 4&#215;4 de apoyo durante todo el viaje.<\/li>\n<li>Explicaciones sobre cultura, naturaleza y geolog\u00eda.<\/li>\n<li>Asesoramiento sobre preparaci\u00f3n de los veh\u00edculos.<\/li>\n<li>Reuni\u00f3n preliminar online.<\/li>\n<li>Apoyo y gesti\u00f3n en el paso de fronteras.<\/li>\n<li>Cena de despedida con recuerdo.<\/li>\n<li>Merchandising de la expedici\u00f3n.<\/li>\n<li>Waypoints y rutas para GPS.<\/li>\n<li>Apoyo en ruta.<\/li>\n<\/ul>\n<h5>NO INCLUYE<\/h5>\n<ul>\n<li>Todo lo que no se cite expresamente en \u00abIncluye\u00bb, como por ejemplo las comidas del medio d\u00eda, que las haremos aportando en grupo lo que cada uno lleva, o en restaurantes y chiringuitos locales.<\/li>\n<li>Gasoil.<\/li>\n<li>Alquiler de 4&#215;4.<\/li>\n<li>Bebidas en los hoteles.<\/li>\n<li>Comida en el Valle de Ourika.<\/li>\n<li>Gastos de aparcamiento de los veh\u00edculos.<\/li>\n<li>Paseo de dromedario por las dunas. (Solicitar antes de salir. + 25 \u20ac aprox.)<\/li>\n<\/ul>\n<h4>PRECIO POR PERSONA en 4X4 CON CONDUCTOR:<\/h4>\n<ul>\n<li>Cada adulto en pareja:\u00a0<strong>2150<\/strong> \u20ac\u00a0(precio de cada uno de los dos primeros ocupantes, compartiendo habitaci\u00f3n y 4&#215;4).<\/li>\n<li>Consultar adultos en individual, j\u00f3venes menores de edad y ni\u00f1os menores de 12 a\u00f1os.\u00a0<\/li>\n<\/ul>\n<p>Incluye: paso del estrecho en ferry como pasajero, alquiler 4&#215;4 con conductor. No incluye: el gasoil, que ser\u00e1 a medias entre los viajeros del veh\u00edculo.<\/p>\n<p>CONSULTAR PRECIOS EN AVI\u00d3N, ALQUILANDO 4X4 O ACAMPANDO (OVERLAND)<\/p>\n<p>Puedes reservar ahora por <strong>500 \u20ac<\/strong> por coche y pagar el resto antes de la salida por transferencia. Debe adquirirse una reserva coche \u00fanicamente.<\/p>\n<\/div>\n<p><p>\n        <a href=\"\/web\/comprar\/reserva-dunas-raid-marruecos\/\">RESERVAR AHORA<\/a>\n    <\/p>\n<\/p>\n<div>\n<h4>OTRA OPCI\u00d3N: MARRUECOS 4X4 A TU AIRE.\u00a0<\/h4>\n<p>Es posible tambi\u00e9n ofrecerte un viaje tur\u00edstico a medida con los alojamientos, el recorrido y el gu\u00eda (si lo deseas) concertado de antemano. Tanto si eliges la modalidad riads-kasbahs-hoteles, como si decides modalidad overlander acampando.\u00a0<\/p>\n<p><strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=+34619324101&amp;text=Buenos%20d%C3%ADas,%20me%20interesa%20Marruecos%204x4%20autoguiado.%20Estas%20son%20mis%20fechas%20preferidas:\">Solicita aqu\u00ed marruecos 4&#215;4 autoguiado con tus propias fechas.\u00a0<\/a><\/strong><\/p>\n<\/div>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/DJI_0206-1200x675-1.jpg\" alt=\"Por las dunas en dromedario\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-2014-779-1536x1020-1.jpg\" alt=\"fiesta en las Dunas\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-50.jpg\" alt=\"Escalera al cielo. Monumentos del Alem\u00e1n\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-4x4-avion-land-cruiser-1260-27.jpg\" alt=\"paisajes Marroqu\u00edes\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-18.jpg\" alt=\"Por Marruecos con Terranatur\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-terranatur-1600-10.jpg\" alt=\"paisajes impresionantes en Marruecos\"><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/web\/wp-content\/uploads\/marruecos-22-66.jpg\" alt=\"Vistas del Saghro en Marruecos\"><\/p>\n<\/li>\n<\/ul>\n<div>Te interesa<\/div>\n<h2>PLANIFICA TU VIAJE<\/h2>\n<div>\n<h3>VIAJE GRUPAL<\/h3>\n<div>\n<p>Eres de los que te gusta compartir viajes, experiencias o vivencias. Este es tu viaje. Ir\u00e1s acompa\u00f1ado de gu\u00edas expertos en naturaleza y 4&#215;4.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n<\/div>\n<div>\n<h3>NO TENGO EXPERIENCIA EN 4X4<\/h3>\n<div>\n<p>\u00a1Bienvenido igualmente! Organizamos <strong><a href=\"https:\/\/terranatur.es\/web\/cursos4x4\/\">cursos 4\u00d74<\/a><\/strong> de octubre a mayo donde te ense\u00f1aremos a sacar el m\u00e1ximo partido a tu m\u00e1quina, aprendiendo con seguridad y si da\u00f1ar tu coche. Adem\u00e1s, durante la expedici\u00f3n todoterreno aprender\u00e1s mucho mientras vas adquiriendo experiencia.\u00a0<\/p>\n<p>En la parte de arriba est\u00e1 indicado el nivel del viaje.<\/p>\n<p>Si tienes dudas de si esta expedici\u00f3n es para ti, <strong><a href=\"https:\/\/api.whatsapp.com\/send?phone=++34619324101&amp;text=Tengo%20dudas%20de%20si%20esta%20expedicion%20es%20para%20mi...\">contacta con nosotros.<\/a><\/strong><\/p>\n<\/p>\n<\/div>\n<\/div>\n<div>\n<h3>COMIDAS <\/h3>\n<div>\n<p>En el precio del viaje por d\u00eda est\u00e1 inclu\u00edda la cena, desayuno y el alojamiento. Las comidas y los aperitivos (almuerzo), lo hacemos en campo con lo que cada cual trae, en ocasiones pararemos en lugares de carretera a comer.<\/p>\n<\/div>\n<\/div>\n<div>\n<h3>\u00bfHay otras fechas? \u00bfPuedo ir por mi cuenta?<\/h3>\n<div>\n<p>Podemos ofrecerte un viaje autoguiado cuando quieras con tus amigos, grupos de varios coches o para vosotros solos. Tambi\u00e9n la posiblidad de contratar gu\u00eda en exclusiva para vuestro viaje. (Consulta).<\/p>\n<\/div>\n<\/div>\n<div>\n<h3>REUNI\u00d3N<\/h3>\n<div>\n<p>Habr\u00e1 una reuni\u00f3n informativa y formativa online, sobre lo que debemos llevar a esta expedici\u00f3n, as\u00ed como para solucionar todas las dudas que se os presenten.<\/p>\n<\/div>\n<\/div>\n<div>\n<h3>NO TENGO 4X4<\/h3>\n<div>\n<p>No te preocupes. Es un viaje en el que puedes alquilar un Toyota Land Cruiser kdj 180 \u00abafricano\u00bb.<\/p>\n<p>Tambi\u00e9n en este viaje puedes venir de pasajero con conductor.\u00a0<\/p>\n<p>Somos instructores todoterreno. Bienvenidos.<\/p>\n<\/div>\n<\/div>\n<ul>\n<li>\n<h3>Normas y Recomendaciones de Seguridad<\/h3>\n<div>\n<p>La participaci\u00f3n en nuestras actividades de turismo 4&#215;4 requiere el cumplimiento de las siguientes normas de seguridad, respeto medioambiental y conducta responsable:<\/p>\n<h5>Condiciones Generales y Responsabilidad<\/h5>\n<p>La conducci\u00f3n en veh\u00edculos 4&#215;4 por terrenos naturales presenta riesgos inherentes, especialmente en condiciones adversas como pistas mojadas, embarradas o nevadas. <strong>Terranatur Naturaleza Activa<\/strong>\u00a0act\u00faa como organizadora de la actividad, pero no asume responsabilidad por accidentes derivados de una conducci\u00f3n inadecuada, fallos mec\u00e1nicos del veh\u00edculo o incumplimiento de las normas establecidas.\u00a0<strong>Al participar en esta actividad, asumes la responsabilidad de tu seguridad personal y la de terceros durante toda la ruta<\/strong>.<\/p>\n<p>Para m\u00e1s informaci\u00f3n detallada sobre l\u00edmites de responsabilidad, seguros obligatorios y condiciones espec\u00edficas de participaci\u00f3n,\u00a0<strong>consulta nuestras <a href=\"https:\/\/terranatur.es\/web\/condiciones-generales\/\">Condiciones Generales<\/a> de Terranatur<\/strong>.<\/p>\n<h5>Preparaci\u00f3n T\u00e9cnica del Veh\u00edculo<\/h5>\n<p>Antes del inicio de la ruta aseg\u00farate que est\u00e1 bien mantenido y has reparado todo aquello que pueda dar problemas. Verifica el estado general de tu veh\u00edculo, especialmente neum\u00e1ticos, frenos, transmisiones y direcci\u00f3n. Mant\u00e9n siempre la\u00a0<strong>presi\u00f3n de neum\u00e1ticos adecuada<\/strong>\u00a0para el terreno a recorrer.<\/p>\n<p>En pistas sin asfaltar, conduciremos siempre con la tracci\u00f3n integral (4&#215;4).\u00a0<\/p>\n<p><strong>Desconecta los sistemas electr\u00f3nicos de seguridad<\/strong>\u00a0de tu veh\u00edculo como ABS, ESP y control de estabilidad cuando sea t\u00e9cnicamente posible. Estos sistemas, dise\u00f1ados para carretera, pueden interferir negativamente en la conducci\u00f3n por terrenos irregulares y reducir la tracci\u00f3n efectiva.<\/p>\n<h5>Normas de Conducci\u00f3n y Seguridad Vial<\/h5>\n<h5>Velocidad y Distancias<\/h5>\n<ul>\n<li><strong>Velocidad m\u00e1xima<\/strong>: 40 km\/h en pistas sin asfaltar, frecuentemente muy inferior seg\u00fan las condiciones del terreno.<\/li>\n<li>En espacios protegidos y \u00e1reas reguladas: m\u00e1ximo\u00a0<strong>30 km\/h<\/strong><\/li>\n<li>Mant\u00e9n una\u00a0<strong>distancia de seguridad prudencial<\/strong>\u00a0con el veh\u00edculo precedente.<\/li>\n<li>Especialmente en las <strong>cuestas y en las bajadas pronunciadas<\/strong>, no inicies la maniobra hasta el compa\u00f1ero haya subido o bajado completamente ese tramo.<\/li>\n<li>Circularemos en\u00a0<strong>grupos reducidos<\/strong>: m\u00e1ximo 3-5 veh\u00edculos.<\/li>\n<\/ul>\n<h5>T\u00e9cnica de Conducci\u00f3n<\/h5>\n<ul>\n<li>Adopta una\u00a0<strong>posici\u00f3n de conducci\u00f3n correcta<\/strong>: respaldo recto, brazos en \u00e1ngulo de 90\u00b0, volante sujetado con ambas manos en posici\u00f3n \u00ab10 y 10\u00bb con los pulgares fuera del aro.<\/li>\n<li><strong>Cintur\u00f3n de seguridad abrochado<\/strong>\u00a0en todo momento.<\/li>\n<li>Ojo: <strong>Nada de distracciones<\/strong>.<\/li>\n<li>Aplica una\u00a0<strong>t\u00e9cnica de conducci\u00f3n suave<\/strong>: evita aceleraciones y frenadas bruscas.<\/li>\n<li>En descensos pronunciados, utiliza el <strong>freno motor<\/strong> y mant\u00e9n el control constante del veh\u00edculo. Aprende a \u00abcontravolantear\u00bb si el veh\u00edculo derrapa.<\/li>\n<li>Usa la <strong>reductora<\/strong> cuando veas que el terreno se complica, para salvar obst\u00e1culos, o para no forzar las tracciones en subidas o los frenos en bajadas.<\/li>\n<\/ul>\n<h5>Respeto Medioambiental y Sostenibilidad\u00a0<\/h5>\n<h5>Circulaci\u00f3n Responsable<\/h5>\n<ul>\n<li><strong>Circula exclusivamente por pistas y caminos perfectamente delimitados<\/strong>. Est\u00e1 terminantemente prohibida la circulaci\u00f3n campo a trav\u00e9s.<\/li>\n<li>Cuando te detengas, no bloquees la pista, pero evita pisar praderas o zonas con vegetaci\u00f3n.<\/li>\n<li>No invadas propiedades privadas ni terrenos de cultivo<\/li>\n<li>Respeta absolutamente la vegetaci\u00f3n existente:\u00a0<strong>no deteriores ni cortes vegetaci\u00f3n. <\/strong>\u00abCada raya en la pintura cuenta una historia\u00bb no lo olvides.<\/li>\n<li><strong>Prohibido realizar trompos, derrapes o subir por laderas sin camino<\/strong> marcado.<\/li>\n<li>Mejora tus destrezas, participando en nuestros <a href=\"https:\/\/terranatur.es\/web\/cursos4x4\/\"><strong>cursos 4&#215;4 <\/strong><\/a>antes de ir de viaje.<\/li>\n<\/ul>\n<h5>Protecci\u00f3n de la Fauna y Tranquilidad<\/h5>\n<ul>\n<li><strong>Reduce la velocidad<\/strong>\u00a0significativamente al acercarte a personas y\/o animales. Detente si es necesario<\/li>\n<li><strong>No utilices altavoces, claxon o sirenas<\/strong>, excepto por motivos estrictos de seguridad.<\/li>\n<li><strong>Evita la m\u00fasica en las paradas.<\/strong> La mayor\u00eda de los otros participantes buscan la calma y el silencio en este tipo de rutas.<\/li>\n<li>Mant\u00e9n el\u00a0<strong>dispositivo silenciador del escape<\/strong>\u00a0en perfecto estado.<\/li>\n<li><strong>No pares nunca sobre hierba seca<\/strong>. Puede incendiarse tu veh\u00edculo.<\/li>\n<li><strong>Evita producir ruidos<\/strong> injustificados que puedan perturbar la fauna silvestre.<\/li>\n<\/ul>\n<h5>Gesti\u00f3n de Residuos<\/h5>\n<ul>\n<li><strong>Prohibido arrojar cualquier objeto<\/strong>\u00a0al exterior del veh\u00edculo: latas, envases, colillas, etc.<\/li>\n<li>Practica la filosof\u00eda Scout <strong>\u00abdeja el lugar mejor de como lo encontraste\u00bb<\/strong>: que no se note que hemos pasado por all\u00ed, incluso recoge lo que visualmente te moleste, aunque sea de otros.<\/li>\n<li>Recoge todos tus residuos y depos\u00edtalos en lugares apropiados.<\/li>\n<\/ul>\n<h5>Normas de Convivencia y Cortes\u00eda en el Monte<\/h5>\n<h5>Prioridad y Respeto a Otros Usuarios\u00a0<\/h5>\n<p><strong>Damos siempre prioridad absoluta al resto de usuarios del monte<\/strong>, deteni\u00e9ndonos completamente a su paso cuando sea necesario. Esto incluye especialmente a:<\/p>\n<ul>\n<li><strong>Senderistas<\/strong>\u00a0y monta\u00f1eros<\/li>\n<li><strong>Ciclistas<\/strong>\u00a0de monta\u00f1a<\/li>\n<li><strong>Jinetes<\/strong>\u00a0<strong>y amazonas<\/strong><\/li>\n<li><strong>Motoristas<\/strong> de trial, trail o enduro<\/li>\n<li><strong>Quads<\/strong>\u00a0y otros veh\u00edculos todo terreno<\/li>\n<\/ul>\n<h5>Protocolo de Cortes\u00eda<\/h5>\n<p>Cuando te encuentres con otros usuarios del monte:<\/p>\n<ol>\n<li><strong>Avisa cort\u00e9smente cu\u00e1ntos veh\u00edculos vais a pasar<\/strong>: \u00abBuenos d\u00edas, somos 4 coches, vamos a pasar\u00bb<\/li>\n<li><strong>Saluda siempre con educaci\u00f3n y respeto<\/strong><\/li>\n<li><strong>Inter\u00e9sate por su seguridad<\/strong>\u00a0cuando sea apropiado: \u00ab\u00bfTodo bien? \u00bfNecesit\u00e1is ayuda?\u00bb<\/li>\n<li><strong>En caso de grupos grandes<\/strong>, pregunta si necesitan algo o si todo va bien<\/li>\n<li><strong>Mant\u00e9n una actitud amigable<\/strong>\u00a0que represente los valores de Terranatur<\/li>\n<\/ol>\n<h5>Otras Normas de Convivencia.\u00a0<\/h5>\n<ul>\n<li><strong>Cierra siempre todos los portillos ganaderos<\/strong>\u00a0tras el paso del grupo<\/li>\n<li>Respeta las\u00a0<strong>se\u00f1ales de tr\u00e1fico y las indicaciones de agentes medioambientales<\/strong>.<\/li>\n<li>En caso de encontrar <strong>ganado<\/strong> en el camino, reduce la velocidad al m\u00ednimo y espera pacientemente. Desde la ventanilla trata de animar a los animales a apartarse, dando palmadas en la chapa del coche o hablando en voz alta.\u00a0<\/li>\n<\/ul>\n<h5>Pol\u00edtica de Imagen y Derechos\u00a0<\/h5>\n<p>Salvo indicaci\u00f3n expresa en contrario, tu participaci\u00f3n en la actividad implica la\u00a0<strong>autorizaci\u00f3n para el uso<\/strong>\u00a0de fotograf\u00edas y v\u00eddeos tomados durante la ruta.\u00a0<strong>Para conocer los detalles completos sobre el tratamiento de tu imagen y datos personales, consulta nuestra <a href=\"https:\/\/terranatur.es\/web\/privacidad\/\">pol\u00edtica de privacidad<\/a>.<\/strong>\u00a0Terranatur podr\u00e1 utilizarlas para:<\/p>\n<ul>\n<li>Facilitarte el acceso a las im\u00e1genes para tu uso personal.<\/li>\n<li>Promoci\u00f3n y divulgaci\u00f3n de la empresa en Internet y redes sociales.<\/li>\n<li>Material promocional y educativo sobre turismo responsable y conducci\u00f3n 4&#215;4.<\/li>\n<\/ul>\n<h5>Compromiso con la Excelencia<\/h5>\n<p>Tu experiencia es fundamental para nuestro crecimiento.\u00a0<strong>Agradecemos sinceramente tus comentarios y valoraciones<\/strong>\u00a0en Google, Facebook y otras plataformas. Tus opiniones nos ayudan a mejorar continuamente nuestros servicios y a ofrecer experiencias de mayor calidad a futuros participantes.<\/p>\n<p><strong>Recuerda<\/strong>: El turismo 4&#215;4 responsable es compatible con la conservaci\u00f3n del medio ambiente. Sigamos siendo\u00a0<strong>embajadores de la naturaleza<\/strong>\u00a0y demostremos que es posible disfrutar de la aventura respetando nuestro entorno natural.<\/p>\n<p><strong>Terranatur Naturaleza Activa SLU<\/strong>\u00a0&#8211; Turismo de naturaleza sostenible y responsable.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>Avisos, organizaci\u00f3n y pol\u00edtica de cancelaci\u00f3n.<\/h3>\n<div>\n<ul>\n<li><strong>\u00a0<\/strong>Se puede consultar la informaci\u00f3n en materia administrativa y sanitaria en <a href=\"https:\/\/www.exteriores.gob.es\/es\/ServiciosAlCiudadano\/paginas\/detalle-recomendaciones-de-viaje.aspx?trc=marruecos\"> https:\/\/www.exteriores.gob.es\/es\/ServiciosAlCiudadano\/paginas\/detalle-recomendaciones-de-viaje.aspx?trc=marruecos<\/a>.<\/li>\n<li>\n<p>El viajero deber\u00e1 informar a Terranatur, con anterioridad a la contrataci\u00f3n, de aquellas solicitudes, peticiones o necesidades especiales que le fueren de aplicaci\u00f3n.<\/p>\n<\/li>\n<li>\n<p>La informaci\u00f3n legal aplicable a la comercializaci\u00f3n del viaje combinado se encuentra a disposici\u00f3n de los consumidores en las <a href=\"https:\/\/terranatur.es\/web\/condiciones-generales\/\">condiciones generales<\/a><\/p>\n<\/li>\n<li>\n<p>La conducci\u00f3n 4\u00d74 conlleva riesgos inherentes. Terranatur dispone de seguro de responsabilidad civil, pero<span>\u00a0<\/span><strong>no se responsabiliza de accidentes o da\u00f1os<\/strong><span>\u00a0<\/span>ocasionados por tu conducci\u00f3n o decisiones.<\/p>\n<\/li>\n<li>\n<p>Debes llegar al alojamiento con el<span>\u00a0<\/span><strong>dep\u00f3sito lleno<\/strong>.\u00a0<\/p>\n<\/li>\n<li>\n<p>Formar\u00e1s parte de un equipo de varios veh\u00edculos con puntos de reagrupamiento establecidos.<\/p>\n<\/li>\n<li>\n<p>La organizaci\u00f3n podr\u00e1<span>\u00a0<\/span><strong>modificar el programa o alojamientos<\/strong><span>\u00a0<\/span>por motivos de log\u00edstica o inter\u00e9s del grupo.<\/p>\n<\/li>\n<\/ul>\n<p>Terranatur presta<span>\u00a0<\/span><strong>asistencia b\u00e1sica en ruta<\/strong>, pero ante cualquier rescate o actuaci\u00f3n de emergencia, la iniciativa debe partir del afectado, que colaborar\u00e1 como el que m\u00e1s.\u00a0<\/p>\n<div class=\"el-h2\">\n<h5 data-heading=\"Plazas y Organizaci\u00f3n\" dir=\"auto\">Plazas y Organizaci\u00f3n<\/h5>\n<ul>\n<li data-heading=\"Plazas y Organizaci\u00f3n\" dir=\"auto\"><span style=\"font-size: 16px;\">Las plazas son limitadas. El viaje est\u00e1 organizado por Terranatur Naturaleza Activa SLU (Agencia de Viajes CICMA 3161).<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"el-h2\"><\/div>\n<div class=\"el-h2\">\n<h5 data-heading=\"Comunicaci\u00f3n y Navegaci\u00f3n\" dir=\"auto\"><span class=\"heading-collapse-indicator collapse-indicator collapse-icon\"><\/span>Comunicaci\u00f3n y Navegaci\u00f3n<\/h5>\n<\/div>\n<div class=\"el-ul\">\n<ul class=\"has-list-bullet\">\n<li data-line=\"0\" dir=\"auto\"><span class=\"list-bullet\"><\/span>Lleva tu<span>\u00a0<\/span><strong>emisora de 27 MHz<\/strong><span>\u00a0<\/span>para comunicarte con el grupo. Si no dispones de una, cons\u00faltanos: solemos llevar unidades a la venta.<\/li>\n<li data-line=\"1\" dir=\"auto\"><span class=\"list-bullet\"><\/span>Instala en tu m\u00f3vil una app de navegaci\u00f3n GPS (GAIA GPS, IGN Mapas, OruxMaps, GPX Viewer u otra similar) para seguir la ruta sin problemas.<\/li>\n<\/ul>\n<\/div>\n<div class=\"el-h2\">\n<h5 data-heading=\"Provisiones y Equipamiento\" dir=\"auto\"><span class=\"heading-collapse-indicator collapse-indicator collapse-icon\"><\/span>Provisiones y Equipamiento<\/h5>\n<\/div>\n<div class=\"el-ul\">\n<ul class=\"has-list-bullet\">\n<li data-line=\"0\" dir=\"auto\"><span class=\"list-bullet\"><\/span>Trae<span>\u00a0<\/span><strong>almuerzo y comida<\/strong><span>\u00a0<\/span>para campo ambos d\u00edas; es habitual compartir lo que cada uno lleva.<\/li>\n<li data-line=\"1\" dir=\"auto\"><span class=\"list-bullet\"><\/span>Se recomiendan<span>\u00a0<\/span><strong>botas o zapatillas de trekking<\/strong>, prism\u00e1ticos y c\u00e1mara de fotos.<\/li>\n<\/ul>\n<\/div>\n<div class=\"el-h2\">\n<h5 data-heading=\"Condiciones de Participaci\u00f3n\" dir=\"auto\"><span class=\"heading-collapse-indicator collapse-indicator collapse-icon\"><\/span>Condiciones de Participaci\u00f3n<\/h5>\n<\/div>\n<ul>\n<li class=\"el-p\">Al participar aceptas estas normas y nuestras <strong><a href=\"https:\/\/terranatur.es\/web\/condiciones-generales\/\">condiciones Generales<\/a> de Terranatur<\/strong>, disponible en la web.<\/li>\n<\/ul>\n<div class=\"el-ol\">\n<ul><\/ul>\n<\/div>\n<div class=\"el-h2\">\n<h5 data-heading=\"Pol\u00edtica de Cancelaciones y Reembolsos\" dir=\"auto\"><span class=\"heading-collapse-indicator collapse-indicator collapse-icon\"><\/span>Pol\u00edtica de Cancelaciones y Reembolsos<\/h5>\n<\/div>\n<div class=\"el-ul\">\n<ul class=\"has-list-bullet\">\n<li data-line=\"0\" dir=\"auto\"><span class=\"list-bullet\"><\/span>Se requiere un<span>\u00a0<\/span><strong>anticipo<\/strong><span>\u00a0<\/span>para reservar tu plaza.<\/li>\n<li data-line=\"1\" dir=\"auto\"><span class=\"list-bullet\"><\/span><strong>Cancelaciones 7 d\u00edas antes o menos<\/strong>: no hay devoluci\u00f3n del anticipo.<\/li>\n<li data-line=\"2\" dir=\"auto\"><span class=\"list-bullet\"><\/span>Si el alojamiento no reembolsa tu reserva, se te reclamar\u00e1 el importe \u00edntegro.<\/li>\n<li data-line=\"3\" dir=\"auto\"><span class=\"list-bullet\"><\/span><strong>Fuerza mayor acreditada<\/strong>: devoluci\u00f3n del 100% del importe.<\/li>\n<li data-line=\"4\" dir=\"auto\"><span class=\"list-bullet\"><\/span>Cancelaciones por causas meteorol\u00f3gicas o imputables a la organizaci\u00f3n:<span>\u00a0<\/span><strong>reembolso \u00edntegro<\/strong>.<\/li>\n<\/ul>\n<\/div>\n<div class=\"el-p\">\n<p dir=\"auto\">Consulta nuestras<span>\u00a0<\/span><a href=\"https:\/\/terranatur.es\/web\/condiciones-generales\/\"><strong>Condiciones Generales<\/strong><\/a><span>\u00a0<\/span>para los plazos concretos y otras informaciones esenciales.<\/p>\n<\/div>\n<div class=\"el-p\">\n<p dir=\"auto\"><strong>Terranatur Naturaleza Activa SLU \u2013 CICMA 3161<\/strong><br \/>Tu aventura 4\u00d74, con total transparencia y compromiso.<\/p>\n<\/div>\n<\/div>\n<\/li>\n<li>\n<h3>Protocolo de Asistencia y Evacuaci\u00f3n por Aver\u00eda o Accidente<\/h3>\n<div>\n<p><strong>En caso de aver\u00eda o accidente que impida continuar la ruta, sigue este protocolo:<\/strong><\/p>\n<ol>\n<li><strong> Parada Segura y Comunicaci\u00f3n<\/strong><\/li>\n<\/ol>\n<p>1.1 Det\u00e9n tu 4\u00d74 en un lugar seguro y activa las luces de emergencia.<\/p>\n<p>1.2 Contacta al gu\u00eda o responsable de la ruta v\u00eda emisora de 27 MHz o tel\u00e9fono de la organizaci\u00f3n, indicando tu ubicaci\u00f3n y naturaleza del incidente.<\/p>\n<ol start=\"2\">\n<li><strong> Evaluaci\u00f3n de Riesgos y Espera de Instrucciones<\/strong><\/li>\n<\/ol>\n<p>2.1 Si existe riesgo de agravar la situaci\u00f3n (terreno inestable, gran inclinaci\u00f3n, vuelco fugas, etc.),\u00a0<strong>no intentes mover tu solo el veh\u00edculo<\/strong>.<\/p>\n<p>2.2 Espera las\u00a0<strong>instrucciones expresas del organizador<\/strong>, que acudir\u00e1 de inmediato para evaluar y coordinar la intervenci\u00f3n.<\/p>\n<ol start=\"3\">\n<li><strong> Evacuaci\u00f3n de Ocupantes<\/strong><\/li>\n<\/ol>\n<p>3.1 Primero auxiliamos a los ocupantes para que abandonen el veh\u00edculo con total seguridad.<\/p>\n<p>3.2 Al\u00e9jate de la calzada o pista, buscando refugio tras alg\u00fan elemento natural. Los pasajeros del coche afectado deber\u00e1n estar apartados de la zona de rescate para evitar posibles accidentes.<\/p>\n<ol start=\"4\">\n<li><strong> Rescate Inmediato por la Organizaci\u00f3n<\/strong><\/li>\n<\/ol>\n<p>4.1 La organizaci\u00f3n con tu colaboraci\u00f3n, intentar\u00e1 el\u00a0<strong>rescate y remolque del 4\u00d74<\/strong> antes de nada.<\/p>\n<p>4.2 Sigue las indicaciones del gu\u00eda para el enganche, sujeci\u00f3n de eslingas o cabrestante y maniobras seguras. El rescate ser\u00e1 coordinado por el responsable de la ruta o quien este designe.<\/p>\n<ol start=\"5\">\n<li><strong> Llamada a Asistencia en Carretera<\/strong><\/li>\n<\/ol>\n<p>5.1 Si el rescate con los medios disponibles en ruta no es posible, o el veh\u00edculo no puede reemprender la marcha por aver\u00eda o da\u00f1os, el participante gestionar\u00e1 la llamada a la gr\u00faa o servicio de auxilio autorizado con la ayuda del gu\u00eda.<\/p>\n<p>5.2 Facilita la ubicaci\u00f3n exacta y la descripci\u00f3n del problema.<\/p>\n<ol start=\"6\">\n<li><strong> Reincorporaci\u00f3n al Grupo<\/strong><\/li>\n<\/ol>\n<p>6.1 Te animaremos a que continues el viaje\u00a0<strong>subiendo como pasajero<\/strong> a un veh\u00edculo de la organizaci\u00f3n o al de otro participante que disponga de plazas libres.<\/p>\n<p>6.2 Si decides\u00a0<strong>abandonar la ruta y regresar<\/strong>, esta decisi\u00f3n no da derecho a\u00a0<strong>devoluci\u00f3n<\/strong>\u00a0del coste de la actividad ni de servicios contratados.<\/p>\n<ol start=\"7\">\n<li><strong> Documentaci\u00f3n y Cierre de Incidente<\/strong><\/li>\n<\/ol>\n<p>7.1 Documenta el accidente mediante fotos, videos y una descripci\u00f3n escrita. Compromete a posibles testigos en caso de que sea necesaria una futura declaraci\u00f3n.<\/p>\n<ol start=\"8\">\n<li><strong> Recomendaciones Preventivas<\/strong><\/li>\n<\/ol>\n<ul>\n<li>Revisa antes de la ruta frenos, transmisiones, niveles de l\u00edquidos y presi\u00f3n de neum\u00e1ticos.<\/li>\n<li>Es obligatorio que cada veh\u00edculo venga con al menos dos anclajes de remolque bien sujetos al chasis; uno delantero y otro trasero.<\/li>\n<li>Lleva\u00a0herramientas b\u00e1sicas, gato, fusibles, l\u00edquido anticongelante, aceite de motor, cinta americana, llave de arranque de repuesto, llave para quitar las tuercas (tambi\u00e9n las de seguridad), rueda de repuesto en buen estado y\u00a0botiqu\u00edn de primeros auxilios.<\/li>\n<li>Agua, algo de comida y mantas.<\/li>\n<li>Alguna herramienta de corte.<\/li>\n<li>Mant\u00e9n siempre cargado el tel\u00e9fono m\u00f3vil.<\/li>\n<\/ul>\n<\/div>\n<\/li>\n<\/ul>\n<p><p>\n        <a href=\"\/web\/comprar\/reserva-dunas-raid-marruecos\/\">RESERVAR AHORA<\/a>\n    <\/p>\n<\/p>\n<div>\n<p>.<\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"name\":\"Hero\",\"type\":\"section\",\"props\":{\"height\":\"viewport\",\"height_viewport_offset\":true,\"image\":\"wp-content\/uploads\/atardecer-dunas-scaled.jpg\",\"image_effect\":\"parallax\",\"image_parallax_bgy\":\"-200,0\",\"image_parallax_breakpoint\":\"m\",\"image_parallax_easing\":\"1\",\"image_position\":\"top-center\",\"image_size\":\"cover\",\"image_width\":\"2560\",\"overlap\":true,\"padding_bottom\":\"large\",\"padding_top\":\"large\",\"style\":\"default\",\"text_color\":\"light\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"large\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_color\":\"background\",\"title_element\":\"div\",\"title_style\":\"h3\"}},{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<p>DUNAS RAID IX MARRUECOS.<\/p>\n\n\\n\n\n<p>SEMANA SANTA 2026<\/p>\n\n\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_top\":\"remove\",\"maxwidth\":\"2xlarge\",\"title_element\":\"h1\",\"title_style\":\"heading-xlarge\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\",\"margin_bottom\":\"remove\",\"margin_top\":\"remove\",\"maxwidth\":\"large\",\"text_color\":\"danger\",\"text_style\":\"lead\"}}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"slideshow\",\"props\":{\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"nav\":\"dotnav\",\"nav_align\":\"center\",\"nav_breakpoint\":\"s\",\"nav_position\":\"bottom-center\",\"nav_position_margin\":\"medium\",\"overlay_animation\":\"parallax\",\"overlay_position\":\"center-left\",\"show_content\":false,\"show_link\":false,\"show_meta\":false,\"show_thumbnail\":false,\"show_title\":false,\"slidenav\":\"default\",\"slidenav_breakpoint\":\"s\",\"slidenav_margin\":\"medium\",\"slidenav_outside_breakpoint\":\"xl\",\"slideshow_animation\":\"fade\",\"slideshow_autoplay\":true,\"slideshow_autoplay_interval\":\"5\",\"slideshow_autoplay_pause\":true,\"slideshow_kenburns\":\"alternate\",\"slideshow_min_height\":300,\"thumbnav_height\":\"75\",\"thumbnav_svg_color\":\"emphasis\",\"thumbnav_width\":\"100\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-22-32.jpg\",\"image_alt\":\"Descanso en el Shagro\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-22-57.jpg\",\"image_alt\":\"La Momia. Gara de Medouar\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/dromedarios-erg.jpg\",\"image_alt\":\"Dromedarios por el Erg Chebbi. Marruecos\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-terranatur-1600-05.jpg\",\"image_alt\":\"Atravesando el Shagro\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-22-67.jpg\",\"image_alt\":\"Tener\u00edas de Fez\"}}]}]}]}]},{\"name\":\"CAJA FOTO + LETRERO SOMBREIMPRESO\",\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"overlap\":false,\"padding_bottom\":\"none\",\"padding_top\":\"none\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"center-right\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"xlarge\"},\"children\":[{\"type\":\"row\",\"props\":{\"column_gap\":\"collapse\",\"layout\":\"1-2,1-2\",\"row_gap\":\"collapse\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"image\",\"props\":{\"animation\":\"parallax\",\"block_align\":\"right\",\"height_expand\":false,\"height_viewport\":false,\"image\":\"wp-content\/uploads\/LOGO-DUNAS-RAID-2025-IX-1.png\",\"image_alt\":\"Logo tipo Dunas Raid IX. Marruecos 4x4 con Terranatur\",\"image_svg_color\":\"emphasis\",\"image_width\":580,\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"-100,-240\",\"position\":\"relative\",\"position_left\":\"0\",\"text_align\":\"right\"}},{\"type\":\"image\",\"props\":{\"animation\":\"parallax\",\"block_align\":\"right\",\"image\":\"wp-content\/uploads\/palmeras-verticas.jpg\",\"image_alt\":\"palmeral\",\"image_box_decoration\":\"default\",\"image_svg_color\":\"emphasis\",\"image_width\":\"600\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"maxwidth\":\"xlarge\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"-100,-240\",\"text_align\":\"right\",\"visibility\":\"m\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"panel\",\"props\":{\"animation\":\"parallax\",\"content\":\"\n\n<p><strong>Semana Santa:<\/strong> (26) 27 marzo - (5) 6 de abril de 2026<\/p>\n\n\\n\n\n<p>Riads, Kasbahs y Lodges con encanto y m\u00e1xima calidad hotelera en su zona.\n\nGu\u00edas: Jaime Roset y Paloma Mill\u00e1n .<\/p>\n\n\\n\n\n<h4>\u00a1ALGUNAS PLAZAS LIBRES DE \u00daLTIMA HORA!<\/h4>\n\n\\n\n\n<h5>Viajeros hasta la fecha:<\/h5>\n\n\\n\n\n<ol>\\n\n\n<li><strong>Claudio y Br\u00edgida.<\/strong> Mitsubishi Montero.<span class=\\\"Apple-tab-span\\\"> <\/span>Ciudad Real.<\/li>\n\n\\n\n\n<li><strong>Jos\u00e9 Ignacio y Pilar<\/strong>.<span class=\\\"Apple-tab-span\\\"> <\/span>Land Rover Defender.<span class=\\\"Apple-tab-span\\\"> <\/span>Ciudad Real.<\/li>\n\n\\n\n\n<li><strong>Pere y Francesc. <\/strong>(Blauet)\u00a0Toyota Land Cruiser 95. Rub\u00ed.<\/li>\n\n\\n\n\n<li><strong>Miguel, Ilenia y Mateo.<\/strong> Nissan Terrano II. Madrid.<\/li>\n\n\\n\n\n<li><strong>Paco, Raquel y Guille<\/strong>\u00a0(17) . Mitsubishi Montero. Madrid<\/li>\n\n\\n\n\n<li><strong>Pepe, Irene y Ana<\/strong> (Padawan). Land Rover Discovery 4. Valdepe\u00f1as.<\/li>\n\n\\n\n\n<li><strong>Mar\u00eda, Fernando, Gonzalo y Albert<\/strong>o (Padawan). Land Rover Discovery 4. Valdepe\u00f1as.<\/li>\n\n\\n\n\n<li><strong>Roberto y Monica. <\/strong>Isuzu Dmax Extrem. Asturias.<\/li>\n\n\\n\n\n<li><strong>Jorge, Sara y Leo (16)<\/strong>. Toyota Land Cruiser. Cantabria.<\/li>\n\n\\n\n\n<li><strong>Carola, Jos\u00e9 Mar\u00eda y Dani (10).<\/strong> Land Rover Defender. Madrid.<\/li>\n\n\\n\n\n<li><strong>Mirian, Ivan, Nico (13), Max (9)<\/strong>. (Beskar) Jeep Wrangler. Barcelona<\/li>\n\n\\n\n\n<li>...<\/li>\n\n\\n\n\n<li><strong>Goyo (Gu\u00eda-conductor).<\/strong> Kia Sorento. Toledo.<\/li>\n\n\\n\n\n<li><strong>Jaime y Paloma (Gu\u00edas).<\/strong> Toyota Hilux. Madrid.<\/li>\n\n\\n<\/ol>\n\n\\n\n\n<ol><\/ol>\n\n\\n\n\n<ol><\/ol>\n\n\\n\n\n<ol><\/ol>\n\n\\n\n\n<p>\u00a1<strong>LAS DUNAS<\/strong>!... Cuando las descubres, algo cambia en ti. Dicen que amamos lo que no tenemos. Las dunas son una provocaci\u00f3n a la aventura. Quiz\u00e1 son uno de los paisajes m\u00e1s bellos y sugestivos que puedas encontrar en el mundo. La sensaci\u00f3n de caminar o surfear en tu 4x4 sobre ellas, no tiene comparaci\u00f3n alguna.<\/p>\n\n\\n\n\n<p>Por el camino, visitaremos lugares sorprendentes mientras nos imbuimos en la cultura bereber y \u00e1rabe. \u00bfTe gusta la fotograf\u00eda o grabar v\u00eddeos? Has llegado al lugar correcto: aqu\u00ed podr\u00e1s disfrutar tu afici\u00f3n a tope.<\/p>\n\n\\n\n\n<p>Adem\u00e1s, si vienes con familia, para tus hijos ser\u00e1 una ocasi\u00f3n \u00fanica. Para ti, tambi\u00e9n.<\/p>\n\n\\n\n\n<p>Este viaje es como un regreso al pasado y los paisajes te dejar\u00e1n encantado.<\/p>\n\n\\n\n\n<h5>FORMAS DE VIAJAR:<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li>EN TU PROPIO 4X4\u00a0<\/li>\n\n\\n\n\n<li>DE PASAJEROS EN 4x4 CON UN GU\u00cdA CONDUCTOR\u00a0<\/li>\n\n\\n\n\n<li>ALQUILANDO ALL\u00cd UN 4X4<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<ul>\\n\n\n<li>N\u00daMERO DE 4X4 PARTICIPANTES LIMITADO.<\/li>\n\n\\n\n\n<li>POR AGILIDAD, SE FORMAR\u00c1N SUBGRUPOS DE 7-8 COCHES.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>RESERVA AHORA tu viaje CON TODA CONFIANZA.<\/h5>\n\n\\n\n\n<p>Haremos rutas 4x4 y pistas especiales por paisajes que te dejar\u00e1n sin aliento\u2026ven a la aventura sahariana con nosotros.<strong>\u00a0<\/strong><strong>Incluye Asilah, Catedral de Rocas de Imsfrane, Garganta de Asiff Melloul, Cascadas de Ouzoud, Valle de Ourika (alto Atlas), Valle de Ounila, Ait Ben Haddou, Ouarzazate, Gargantas del Dades y Todra, Tinehir, Ciudad Perdida, Erg Ouzina, Erg Chebbi, <\/strong><strong>Bosque de Cedros, Fez, Chefchaouen, <\/strong><strong>cursillo de conducci\u00f3n en dunas y mucho m\u00e1s.\u00a0<\/strong><\/p>\n\n\\n\n\n<p><b>El itinerario definitivo est\u00e1 sujeto a confirmaci\u00f3n.<\/b><\/p>\n\n\\n\n\n<p>Nos gusta contactar con la poblaci\u00f3n local. Sentir\u00e1s lo acogedores que son nuestros amigos bereberes, \u00e1rabes y n\u00f3madas. \u00a0<\/p>\n\n\\n\n\n<p>NOTA IMPORTANTE: <strong>SOLO 4X4 CON REDUCTORA,\u00a0 RUEDAS MIXTAS M\u00cdNIMO 50-50, Y LLANTAS DE DE 18' O MENOS.<\/strong><\/p>\n\n\\n\n\n<p>Naturaleza: 4\/5\u00a0\u00a0 Gastronom\u00eda: 4\/5\u00a0\u00a0 Ni\u00f1os: \u00a1ok!<\/p>\n\n\\n\n\n<div class=\\\"uk-child-width-1-2 uk-grid-large\\\" uk-grid=\\\"\\\">\\n\n\n<div class=\\\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\\\" uk-grid=\\\"\\\">\\n\n\n<div style=\\\"max-width: 80px;\\\"><img src=\\\"wp-content\/uploads\/trans-alps-about-icon-01.svg\\\" alt=\\\"\\\" uk-svg=\\\"\\\" \/><\/div>\n\n\\n\n\n<div class=\\\"uk-flex uk-flex-center uk-flex-middle\\\" style=\\\"max-width: 80px;\\\">\\n\n\n<div class=\\\"uk-h6\\\">700 km offroad aprox<\/div>\n\n\\n<\/div>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\\\" uk-grid=\\\"\\\">\\n\n\n<div style=\\\"max-width: 80px;\\\"><img src=\\\"wp-content\/uploads\/trans-alps-about-icon-02.svg\\\" alt=\\\"\\\" uk-svg=\\\"\\\" \/><\/div>\n\n\\n\n\n<div class=\\\"uk-flex uk-flex-center uk-flex-middle\\\" style=\\\"max-width: 80px;\\\">\\n\n\n<div class=\\\"uk-h6\\\">10 d\u00edas<\/div>\n\n\\n<\/div>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\\\" uk-grid=\\\"\\\">\\n\n\n<div style=\\\"max-width: 80px;\\\"><img src=\\\"wp-content\/uploads\/trans-alps-about-icon-03.svg\\\" alt=\\\"\\\" uk-svg=\\\"\\\" \/><\/div>\n\n\\n\n\n<div class=\\\"uk-flex uk-flex-center uk-flex-middle\\\" style=\\\"max-width: 80px;\\\">\\n\n\n<div class=\\\"uk-h6\\\">Dunas, Hammadas, Atlas<\/div>\n\n\\n<\/div>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"uk-grid-collapse uk-child-width-1-2@s uk-margin-bottom\\\" uk-grid=\\\"\\\">\\n\n\n<div style=\\\"max-width: 80px;\\\"><img src=\\\"wp-content\/uploads\/trans-alps-about-icon-04.svg\\\" alt=\\\"\\\" uk-svg=\\\"\\\" \/><\/div>\n\n\\n\n\n<div class=\\\"uk-flex uk-flex-center uk-flex-middle\\\" style=\\\"max-width: 80px;\\\">\\n\n\n<div class=\\\"uk-h6\\\">Dificultad: 3-4\/5 seg\u00fan etapa<\/div>\n\n\\n<\/div>\n\n\\n<\/div>\n\n\\n<\/div>\n\n\",\"content_column_breakpoint\":\"m\",\"css\":\"@media (max-width: 959px) {\\n    .el-element { position: static !important; }\\n}\",\"image\":\"\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"\",\"margin_top\":\"\",\"maxwidth\":\"xlarge\",\"maxwidth_breakpoint\":\"l\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_padding\":\"large\",\"panel_style\":\"card-default\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"-200,0\",\"position\":\"relative\",\"position_left\":\"-50\",\"text_align\":\"left\",\"title\":\"Dos desiertos, un destino: Descubre Marruecos en 4x4\",\"title_align\":\"top\",\"title_element\":\"h2\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_style\":\"h1\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"RESERVAR AHORA\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"comprar\/reserva-dunas-raid-marruecos\/\"}}]}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"PLAN DE VIAJE\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"link_target\":true,\"title_element\":\"h1\",\"title_style\":\"heading-large\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Aqu\u00ed tienes el itinerario y el programa de viaje con tu propio 4x4, acompa\u00f1ado siempre de gu\u00edas expertos e instructores 4x4. Dentro de los viajes de aventura a Marruecos, es sin duda uno de los m\u00e1s completos en 11 etapas.<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"wp-content\/uploads\/MAPA-MARRUECOS-ITINERARIO-ETAPAS.jpg\",\"image_alt\":\"itinerario Marruecos Semana Santa 2026\",\"image_svg_color\":\"emphasis\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}},{\"type\":\"headline\",\"props\":{\"content\":\"ITINERARIO VIAJE DUNAS RAID IX\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_element\":\"h1\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Todos los a\u00f1os hacemos modificaciones para <strong>mejorar<\/strong> y hacer m\u00e1s interesante el recorrido, ya que <strong>nuestros viajeros\u00a0 frecuentemente repiten<\/strong> con nosotros edici\u00f3n tras edici\u00f3n; por eso, hasta un mes antes de la salida, <strong>este recorrido puede verse alterado<\/strong>.\u00a0<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"accordion\",\"props\":{\"collapsible\":true,\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"show_image\":true,\"show_link\":true},\"children\":[{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Cruzamos el estrecho en el primer ferry rumbo a Marruecos. Salimos de <strong>Algeciras<\/strong> para llegar a <strong>Tanger Med<\/strong>.\u00a0<\/p>\n\n\\n\n\n<p>Desde ah\u00ed por carretera hasta <strong>Asilah<\/strong>, la \\\"perla de Marruecos\\\" peque\u00f1a y preciosa poblaci\u00f3n costera donde comeremos.<\/p>\n\n\\n\n\n<p>Ruta por carretera hasta <strong>Mekness<\/strong> comenzando a descubrir este interesante pa\u00eds.\u00a0<\/p>\n\n\\n\n\n<p>Aposentamiento en el hotel, cena y si te apetece: tiempo libre para una <strong>visita nocturna a Mekness<\/strong>.\u00a0<\/p>\n\n\",\"image\":\"wp-content\/uploads\/asilah-marruecos-terranatur.jpg\",\"image_alt\":\"Ashila Marruecos\",\"title\":\"D\u00cdA 1 (27 DE MARZO 2026). ALGECIRAS - PASO DEL ESTRECHO - MEKNESS\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Desde <strong>Mekness<\/strong> nos dirigimos al Atlas Medio pasando por el Parque Nacional de <strong>Jenifra<\/strong>.\u00a0<\/p>\n\n\\n\n\n<p>Llegando a las monta\u00f1as, comienza una ruta por visitando <strong>las fuentes del OUM RABIA<\/strong>, y el<strong> Bosque de Cedros<\/strong> haciendo una ruta de monta\u00f1a completamente nueva, que nos llevar\u00e1 hasta el coraz\u00f3n del Atlas en <strong>Imilchil<\/strong>.<\/p>\n\n\",\"image\":\"wp-content\/uploads\/catedras-rocas-imsfrane.jpg\",\"image_alt\":\"Catedral de Rocas de Imsfrane. Marruecos\",\"title\":\"DIA 2 (28 MARZO 2026). MEKNESS - PARQUE NACIONAL DE JENIFRA - IMILCHIL\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Seguimos de ruta 4x4 hasta dos de las joyas escondidas que m\u00e1s nos gustan: <strong>La Catedral de Rocas de Imsfrane<\/strong> y la Garganta de <strong>Asiff Melloul<\/strong>, una de las m\u00e1s bellas y menos conocidas del pa\u00eds.<\/p>\n\n\\n\n\n<p>Siguiendo por carreteras de monta\u00f1a por el Atlas descubriremos la cascada m\u00e1s alta del norte de \u00c1frica, en las <strong>Cascadas de Ouzoud<\/strong>, una verdadera belleza y rareza geol\u00f3gica.\u00a0<\/p>\n\n\\n\n\n<p>Noche en <strong>Palais du Ouzoud.\u00a0<\/strong><\/p>\n\n\",\"image\":\"wp-content\/uploads\/cascadas-de-ouzoud.jpg\",\"image_alt\":\"Cascada de Ouzoud. Marruecos.\",\"title\":\"D\u00cdA 3 (29 MARZO 2026). IMILCHIL - CATEDRAL DE ROCAS - CASCADAS DE OUZOUD\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>En esta etapa nos dirigimos al m\u00e1gico <strong>valle de Ourika<\/strong>, uno de nuestros destinos m\u00e1s divertidos y singulares. Por la tarde entraremos desde <strong>Oukamaiden<\/strong> para la conquista del paso en el alto Atlas a m\u00e1s de <strong>3000<\/strong> metros por donde pasa la pista.\u00a0<\/p>\n\n\\n\n\n<p>El objetivo es recorrer la zona hasta<strong> Seti Fatma<\/strong> y cenar ah\u00ed.\u00a0<\/p>\n\n\\n\n\n<p>Noche en un riad cercano.<\/p>\n\n\",\"image\":\"wp-content\/uploads\/marruecos-22-88.jpg\",\"image_alt\":\"Valle de Ourika 4x4\",\"title\":\"D\u00cdA 4 (30 MARZO 2026). CASCADAS DE OUZOUD-OURIKA\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Nos dirigimos a atravesar el <strong>Alto Atlas<\/strong> por carreteras de monta\u00f1a impresionantes. Cambiamos de vertiente y entramos en el sur de Marruecos, cruzando el puerto del <strong>Tizi'n Tischka<\/strong>. Visitaremos la Kasbah m\u00e1s famosa: <strong>Ait Ben Haddou<\/strong>, uno de los escenarios m\u00e1s legendarios de pel\u00edculas.\u00a0\u00a0<\/p>\n\n\\n\n\n<p>Noche en la Kasbah aut\u00e9ntica dentro de Ait Ben Haddou.\u00a0<\/p>\n\n\",\"image\":\"wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur16.jpg\",\"image_alt\":\"Palmeral \",\"title\":\"D\u00cdA 5 (31 MARZO 2026). VALLE DE OURIKA- AIT BEN HADDOU\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Bonita pista hasta <strong>Ouarzazate<\/strong>, la meca del cine.\u00a0<\/p>\n\n\\n\n\n<p>Posible visita voluntaria a los estudios cinematogr\u00e1ficos.\u00a0<\/p>\n\n\\n\n\n<p>Dedicamos esta jornada para explorar las magn\u00edficas Gargantas del <strong>Todra y del Dades<\/strong>, incluyendo el pueblo de <strong>Tinerhir<\/strong>, con sus ruinas y palmerales inolvidables.<\/p>\n\n\\n\n\n<p>Noche en riad tradicional.<\/p>\n\n\",\"image\":\"wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur12.jpg\",\"image_alt\":\"shagro. Antiatlas marroqui\",\"title\":\"D\u00cdA 6 (1 ABRIL 2026). AIT BEN HADDOU - DADES - TODRA\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>En este trayecto tenemos el resto de atravesar la tortuosa cordillera volc\u00e1nica del <strong>Shagro<\/strong>, un laberinto de pistas que no os dejar\u00e1 indiferentes.\u00a0<\/p>\n\n\\n\n\n<p>Cruzando las zonas subdes\u00e9rticas llegaremos a la <strong>ciudad perdida,<\/strong> antesala a las <strong>dunas del Erg Ouzina<\/strong>.\u00a0<\/p>\n\n\\n\n\n<p>Por la noche, observaci\u00f3n de estrellas y t\u00e9cnicas b\u00e1sicas de orientaci\u00f3n astron\u00f3mica. Estamos en un <strong>destino Starlight<\/strong> \u00fanico!!!<br \/><strong><\/strong><\/p>\n\n\\n\n\n<p><strong>Alojamiento y cena:<\/strong> Riad Ouzina TGM, Riad Rimal o khaimas bereberes aut\u00e9nticas.<\/p>\n\n\",\"image\":\"wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur32.jpg\",\"image_alt\":\"doradas dunas del Erg Ouzina\",\"title\":\"D\u00cdA 7 (2 ABRIL 2026)  DADES - JBEL SHAGRO - DUNAS ERG OUZINA\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Nos dirigimos al <strong>Erg Chebbi<\/strong> tras un <strong>cursillo de conducci\u00f3n en dunas<\/strong> en el\u00a0<strong>Erg Ouzina.<\/strong><\/p>\n\n\\n\n\n<p>Descubrimos los secretos del mayor <strong>mar de Dunas de Marruecos.\u00a0<\/strong><\/p>\n\n\\n\n\n<p>Noche en <strong>Kasbah Yasmina<\/strong>.\u00a0<\/p>\n\n\\n\n\n\n\n\",\"image\":\"wp-content\/uploads\/2015-03-marruecos-1426-scaled-2.jpg\",\"image_alt\":\"Dunas de Merzouga con Terranatur\",\"title\":\" D\u00cdA 8 (3 ABRIL 2026). ERG OUZINA - ERG CHEBBI \"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Disfrutamos del <strong>amanecer<\/strong> en las dunas antes de emprender una bonita etapa hasta <strong>Midelt<\/strong>. Por la ma\u00f1ana aprovecharemos para navegar de nuevo por las dunas.\u00a0<\/p>\n\n\\n\n\n<p>Recorrido por carretera atravesando la <strong>garganta del Fiz<\/strong>.<\/p>\n\n\\n\n\n<p>Noche en el <strong>hotel Taddart de Midelt.<\/strong><\/p>\n\n\",\"image\":\"wp-content\/uploads\/Marruecos-4x4-dunas-raid-Terranatur14.jpg\",\"image_alt\":\"Desiertos pedregosos\",\"title\":\"DIA 9 (4 ABRIL 2026). DUNAS DEL ERG CHEBBI - MIDELT\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Salimos de Midelt camino de <strong>Fez<\/strong>, cruzando <strong>bosques de cedros<\/strong>. El objetivo es comer en la medina de Fez y llegar a cenar a <strong>Chefchaouen<\/strong>, la ciudad a\u00f1il.\u00a0<\/p>\n\n\\n\n\n<p>Noche en <strong>Dar Ba Sidi.<\/strong><\/p>\n\n\\n\n\n<p><strong>CONSULTA EMBARCAR ESA MISMA NOCHE SI LO PREFIERES (NO RECOMENDABLE).<\/strong><\/p>\n\n\",\"image\":\"wp-content\/uploads\/marruecos-terranatur-03.jpg\",\"image_alt\":\"Puesta de sol en Chefchaouen\",\"title\":\"D\u00cdA 10 (5 ABRIL 2026). MIDELT - FEZ - CHEFCHAOUEN\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Salimos desde <strong>Chefchaouen<\/strong>, conocida como la \\\"ciudad azul\\\", rumbo <strong>Tanger Med<\/strong> pasando por <strong>Tetuan<\/strong>.<\/p>\n\n\\n\n\n<p>Cruce del estrecho al llegar a puerto, destino <strong>Algeciras<\/strong>.\u00a0<\/p>\n\n\\n\n\n<p>Fin de nuestra aventura de momento... \ud83d\ude09<\/p>\n\n\",\"image\":\"wp-content\/uploads\/ferry-tarifa.jpg\",\"image_alt\":\"Saliendo hacia Africa\",\"title\":\"D\u00cdA 11 (6 ABRIL 2026) CHEFCHAOUEN - TANGER MED - ALGECIRAS\"}}]}]}]}]},{\"name\":\"Highlights\",\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_bottom\":\"large\",\"padding_top\":\"large\",\"style\":\"default\",\"title\":\"Rutas & aventura\",\"title_breakpoint\":\"xl\",\"title_position\":\"center-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"xlarge\",\"width_expand\":\"right\"},\"children\":[{\"type\":\"row\",\"props\":{\"column_gap\":\"large\",\"layout\":\"1-2,1-2\",\"row_gap\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_large\":\"1-2\"},\"children\":[{\"type\":\"slideshow\",\"props\":{\"animation\":\"parallax\",\"container_padding_remove\":true,\"image_width\":\"1250\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"nav\":\"\",\"nav_align\":\"center\",\"nav_breakpoint\":\"\",\"nav_position\":\"bottom-center\",\"nav_position_margin\":\"large\",\"overlay_animation\":\"parallax\",\"overlay_position\":\"center-left\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\",\"show_content\":true,\"show_link\":true,\"show_meta\":true,\"show_thumbnail\":true,\"show_title\":true,\"slidenav\":\"\",\"slidenav_breakpoint\":\"s\",\"slidenav_margin\":\"medium\",\"slidenav_outside_breakpoint\":\"xl\",\"slideshow_animation\":\"fade\",\"slideshow_autoplay\":true,\"slideshow_autoplay_interval\":\"3\",\"slideshow_autoplay_pause\":true,\"slideshow_box_decoration\":\"mask\",\"slideshow_min_height\":300,\"slideshow_ratio\":\"16:11\",\"thumbnav_height\":\"65\",\"thumbnav_shrink\":true,\"thumbnav_svg_color\":\"emphasis\",\"thumbnav_width\":\"100\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/DSC_0386-1536x1020-1.jpg\",\"image_alt\":\"Por las Hammadas Marroqu\u00edes\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/2017-04-MARRUECOS-2017-2260-1536x1023-1.jpg\",\"image_alt\":\"Paisaje de Erg Ouzina\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-2014-493-1536x1020-1.jpg\",\"image_alt\":\"Dromedario en las dunas de Marruecos\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-2016-182-scaled-1.jpg\",\"image_alt\":\"Por el Atlas Marroqu\u00ed\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/P4161249-2048x1536-1.jpg\",\"image_alt\":\"Pueblo Gwana en Merzouga\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-terranatur-2150-04.jpg\",\"image_alt\":\"Por el Shagro con Terranatur\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-terranatur-1600-07.jpg\",\"image_alt\":\"4x4 en el Saghro\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"order_first\":\"l\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_large\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"animation\":\"parallax\",\"block_align\":\"center\",\"content\":\"Alojamientos con encanto\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"maxwidth\":\"xlarge\",\"maxwidth_breakpoint\":\"l\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\",\"title_color\":\"primary\",\"title_element\":\"div\",\"title_style\":\"h4\"}},{\"type\":\"headline\",\"props\":{\"animation\":\"parallax\",\"block_align\":\"center\",\"content\":\"kasbahs, riads, Khaimas\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_top\":\"remove\",\"maxwidth\":\"xlarge\",\"maxwidth_breakpoint\":\"l\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\",\"title_element\":\"h2\",\"title_style\":\"heading-large\"}},{\"type\":\"text\",\"props\":{\"animation\":\"parallax\",\"block_align\":\"center\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>En Marruecos elegimos siempre lugares muy especiales, algunos \\\"de las mil y una noches\\\", junto con algunos riads que por su localizaci\u00f3n en medio del desierto, suponen una experiencia \u00fanica. Alguna de las noches ser\u00e1 posible dormir en Khaima en pleno desierto.<\/p>\n\n\",\"margin_bottom\":\"medium\",\"margin_top\":\"medium\",\"maxwidth\":\"xlarge\",\"maxwidth_breakpoint\":\"l\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\"}},{\"type\":\"quotation\",\"props\":{\"animation\":\"parallax\",\"author\":\"El equipo Terranatur\",\"block_align\":\"center\",\"content\":\"\n\n<p>\\\"Ven a que te pique el \\\"bicho africano\\\" con nosotros. Una vez conozcas Marruecos y sus dunas, necesitar\u00e1s volver a volver... una y otra vez \\\"<\/p>\n\n\",\"maxwidth\":\"xlarge\",\"maxwidth_breakpoint\":\"l\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\"}}]}]}]},{\"name\":\"Journal\",\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_bottom\":\"none\",\"padding_top\":\"none\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"xlarge\",\"width_expand\":\"left\",\"width_expand_left\":true,\"width_expand_padding_remove\":true},\"children\":[{\"type\":\"row\",\"props\":{\"divider\":false,\"layout\":\"1-2,1-2\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_large\":\"1-2\"},\"children\":[{\"type\":\"image\",\"props\":{\"animation\":\"parallax\",\"container_padding_remove\":true,\"image\":\"wp-content\/uploads\/marruecos-22-53.jpg\",\"image_alt\":\"Fiesta en las dunas\",\"image_box_decoration\":\"mask\",\"image_svg_color\":\"emphasis\",\"image_width\":\"1250\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"vertical_align\":\"middle\",\"width_large\":\"1-2\"},\"children\":[{\"type\":\"headline\",\"props\":{\"animation\":\"parallax\",\"block_align\":\"center\",\"content\":\"PRECIOS VIAJE\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"maxwidth\":\"xlarge\",\"maxwidth_breakpoint\":\"l\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\",\"title_element\":\"h3\",\"title_style\":\"h1\"}},{\"type\":\"text\",\"props\":{\"animation\":\"parallax\",\"block_align\":\"center\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<h4><strong>El total del viaje es la suma del precio de cada persona y el veh\u00edculo. (11 d\u00edas\/9-10 noches).<\/strong><\/h4>\n\n\\n\n\n<h4>PRECIO POR PERSONA en 4X4 particular:<\/h4>\n\n\\n\n\n<ul>\\n\n\n<li>Cada adulto: <strong>1450<\/strong>\u00a0\u20ac<strong> <\/strong>(precio de cada uno de los dos primeros ocupantes, compartiendo habitaci\u00f3n y 4x4).\u00a0<\/li>\n\n\\n\n\n<li>A partir del tercer ocupante en el mismo 4x4 y en la misma habitaci\u00f3n, mayor de 12 a\u00f1os: <strong>1260<\/strong> \u20ac\u00a0<\/li>\n\n\\n\n\n<li>Ni\u00f1o (4-11 a\u00f1os): <strong>998<\/strong> \u20ac<strong><br \/><\/strong><\/li>\n\n\\n\n\n<li>Ni\u00f1o menor de 3 a\u00f1os, consultar.<\/li>\n\n\\n\n\n<li>Adulto solo en su propio 4x4: <strong>2270<\/strong> \u20ac<\/li>\n\n\\n\n\n<li>Un adulto con un menor tienen consideraci\u00f3n como dos adultos.<\/li>\n\n\\n\n\n<li>Consultar extra por habitaci\u00f3n individual si la elige alguno de tus ocupantes.<\/li>\n\n\\n\n\n<li>Consultar alquiler <strong>Toyota Land Cruiser africano<\/strong>.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h4>PRECIO POR VEH\u00cdCULO 4X4 V\u00cdA ALGECIRAS - TANGER MED - ALGECIRAS (paso del Estrecho en ferry y gesti\u00f3n pasajes)<\/h4>\n\n\\n\n\n<ul>\\n\n\n<li>Por veh\u00edculo 4x4 con 1 persona: <strong>385\u00a0\u20ac<\/strong><\/li>\n\n\\n\n\n<li>Por veh\u00edculo 4x4 con 2 personas: <strong>456 \u20ac<\/strong><\/li>\n\n\\n\n\n<li>Por veh\u00edculo 4x4 con 3 personas: <strong>527 \u20ac<\/strong><\/li>\n\n\\n\n\n<li>Por veh\u00edculo 4x4 con 4 personas: <strong>598\u00a0\u20ac<\/strong><\/li>\n\n\\n\n\n<li>Por veh\u00edculo 4x4 con 5 personas: <strong>669 \u20ac<\/strong><\/li>\n\n\\n<\/ul>\n\n\\n\n\n<p>Si deseas embarcar en TARIFA y llegar a TANGER CIUDAD: tiene un suplemento de + 90 \u20ac por adulto y 50 \u20ac ni\u00f1os menores de 11 a\u00f1os en el total del viaje.<\/p>\n\n\\n\n\n<p><strong>Ejemplo del coste total de un viaje<\/strong> para dos adultos y un joven o adulto mayor de 12 a\u00f1os en el mismo 4x4 propio y compartiendo habitaci\u00f3n: 1450 \u20ac + 1450 \u20ac + 1260 \u20ac + 527 \u20ac = <strong>4687\u00a0\u20ac\u00a0<\/strong><\/p>\n\n\\n\n\n<p>Extra habitaci\u00f3n individual: <strong>+310 \u20ac<br \/><\/strong>Extra cruce del estrecho por Tarifa:<strong> + 90 \u20ac<\/strong> por adulto.\u00a0<\/p>\n\n\\n\n\n<h6>Puedes reservar ahora por 500 \u20ac\u00a0 por coche para asegurar vuestra plaza. Salida garantizada a partir de cuatro coches inscritos un mes antes del inicio del viaje.\u00a0<\/h6>\n\n\\n\n\n<ul><\/ul>\n\n\\n\n\n<h5>INCLUYE:<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li>Rutas guiadas en peque\u00f1os grupos guiadas por Marruecos.<\/li>\n\n\\n\n\n<li>Rutas 4x4 en 7 de las etapas (zona sur y en el atlas)<\/li>\n\n\\n\n\n<li>Cursillo de conducci\u00f3n en dunas.<\/li>\n\n\\n\n\n<li>Formaci\u00f3n en orientaci\u00f3n mediante dispositivos m\u00f3viles.<\/li>\n\n\\n\n\n<li>9-10 noches en media pensi\u00f3n cena y desayuno (alojamiento en riads, Kasbahs, khaimas u hoteles). Consulta concertar aparte la noche de antes y la \u00faltima.<\/li>\n\n\\n\n\n<li>Ferry Algeciras - Tanger Med - Algeciras o Tarifa-Tanger Ville-Tarifa (con suplemento).\u00a0<\/li>\n\n\\n\n\n<li>Seguro de viaje TOP con anulaci\u00f3n de ARAG (<a href=\\\"https:\/\/terranatur.es\/web\/wp-content\/uploads\/Resumen_TOP_E14_MARZO_2024.pdf\\\" target=\\\"_blank\\\" rel=\\\"noopener\\\">resumen<\/a> - <a href=\\\"https:\/\/www.i4t.es\/download\/documento?uid=pAJFV6rmoRdvGzQqTylZeqFnImQmMtJM\\\" target=\\\"_blank\\\" rel=\\\"noopener\\\">condiciones generales<\/a>)<\/li>\n\n\\n\n\n<li>Tasas tur\u00edsticas locales.<\/li>\n\n\\n\n\n<li>Gu\u00edas espa\u00f1oles y locales de habla hispana. Idioma de prestaci\u00f3n de servicios en Espa\u00f1ol.<\/li>\n\n\\n\n\n<li>Veh\u00edculo 4x4 de apoyo durante todo el viaje.<\/li>\n\n\\n\n\n<li>Explicaciones sobre cultura, naturaleza y geolog\u00eda.<\/li>\n\n\\n\n\n<li>Asesoramiento sobre preparaci\u00f3n de los veh\u00edculos.<\/li>\n\n\\n\n\n<li>Reuni\u00f3n preliminar online.<\/li>\n\n\\n\n\n<li>Apoyo y gesti\u00f3n en el paso de fronteras.<\/li>\n\n\\n\n\n<li>Cena de despedida con recuerdo.<\/li>\n\n\\n\n\n<li>Merchandising de la expedici\u00f3n.<\/li>\n\n\\n\n\n<li>Waypoints y rutas para GPS.<\/li>\n\n\\n\n\n<li>Apoyo en ruta.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>NO INCLUYE<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li>Todo lo que no se cite expresamente en \\\"Incluye\\\", como por ejemplo las comidas del medio d\u00eda, que las haremos aportando en grupo lo que cada uno lleva, o en restaurantes y chiringuitos locales.<\/li>\n\n\\n\n\n<li>Gasoil.<\/li>\n\n\\n\n\n<li>Alquiler de 4x4.<\/li>\n\n\\n\n\n<li>Bebidas en los hoteles.<\/li>\n\n\\n\n\n<li>Comida en el Valle de Ourika.<\/li>\n\n\\n\n\n<li>Gastos de aparcamiento de los veh\u00edculos.<\/li>\n\n\\n\n\n<li>Paseo de dromedario por las dunas. (Solicitar antes de salir. + 25 \u20ac aprox.)<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h4>PRECIO POR PERSONA en 4X4 CON CONDUCTOR:<\/h4>\n\n\\n\n\n<ul>\\n\n\n<li>Cada adulto en pareja:\u00a0<strong>2150<\/strong> \u20ac\u00a0(precio de cada uno de los dos primeros ocupantes, compartiendo habitaci\u00f3n y 4x4).<\/li>\n\n\\n\n\n<li>Consultar adultos en individual, j\u00f3venes menores de edad y ni\u00f1os menores de 12 a\u00f1os.\u00a0<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<p>Incluye: paso del estrecho en ferry como pasajero, alquiler 4x4 con conductor. No incluye: el gasoil, que ser\u00e1 a medias entre los viajeros del veh\u00edculo.<\/p>\n\n\\n\n\n<p>CONSULTAR PRECIOS EN AVI\u00d3N, ALQUILANDO 4X4 O ACAMPANDO (OVERLAND)<\/p>\n\n\\n\n\n<p>Puedes reservar ahora por <strong>500 \u20ac<\/strong> por coche y pagar el resto antes de la salida por transferencia. Debe adquirirse una reserva coche \u00fanicamente.<\/p>\n\n\",\"margin_bottom\":\"medium\",\"margin_top\":\"medium\",\"maxwidth\":\"xlarge\",\"maxwidth_breakpoint\":\"l\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"50,-150\"}},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"RESERVAR AHORA\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"comprar\/reserva-dunas-raid-marruecos\/\"}}]},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<h4>OTRA OPCI\u00d3N: MARRUECOS 4X4 A TU AIRE.\u00a0<\/h4>\n\n\\n\n\n<p>Es posible tambi\u00e9n ofrecerte un viaje tur\u00edstico a medida con los alojamientos, el recorrido y el gu\u00eda (si lo deseas) concertado de antemano. Tanto si eliges la modalidad riads-kasbahs-hoteles, como si decides modalidad overlander acampando.\u00a0<\/p>\n\n\\n\n\n<p><strong><a href=\\\"https:\/\/api.whatsapp.com\/send?phone=+34619324101&amp;text=Buenos%20d%C3%ADas,%20me%20interesa%20Marruecos%204x4%20autoguiado.%20Estas%20son%20mis%20fechas%20preferidas:\\\">Solicita aqu\u00ed marruecos 4x4 autoguiado con tus propias fechas.\u00a0<\/a><\/strong><\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"slideshow\",\"props\":{\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"nav\":\"dotnav\",\"nav_align\":\"center\",\"nav_breakpoint\":\"s\",\"nav_position\":\"bottom-center\",\"nav_position_margin\":\"medium\",\"overlay_animation\":\"parallax\",\"overlay_position\":\"center-left\",\"show_content\":false,\"show_link\":false,\"show_meta\":false,\"show_thumbnail\":false,\"show_title\":false,\"slidenav\":\"default\",\"slidenav_breakpoint\":\"s\",\"slidenav_margin\":\"medium\",\"slidenav_outside_breakpoint\":\"xl\",\"slideshow_animation\":\"fade\",\"slideshow_autoplay\":true,\"slideshow_autoplay_interval\":\"5\",\"slideshow_autoplay_pause\":true,\"slideshow_kenburns\":\"alternate\",\"slideshow_min_height\":300,\"thumbnav_height\":\"75\",\"thumbnav_svg_color\":\"emphasis\",\"thumbnav_width\":\"100\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/DJI_0206-1200x675-1.jpg\",\"image_alt\":\"Por las dunas en dromedario\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-2014-779-1536x1020-1.jpg\",\"image_alt\":\"fiesta en las Dunas\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-22-50.jpg\",\"image_alt\":\"Escalera al cielo. Monumentos del Alem\u00e1n\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-4x4-avion-land-cruiser-1260-27.jpg\",\"image_alt\":\"paisajes Marroqu\u00edes\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-22-18.jpg\",\"image_alt\":\"Por Marruecos con Terranatur\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-terranatur-1600-10.jpg\",\"image_alt\":\"paisajes impresionantes en Marruecos\"}},{\"type\":\"slideshow_item\",\"props\":{\"image\":\"wp-content\/uploads\/marruecos-22-66.jpg\",\"image_alt\":\"Vistas del Saghro en Marruecos\"}}]}]}]}]},{\"name\":\"Tips\",\"type\":\"section\",\"props\":{\"image\":\"wp-content\/uploads\/trans-alps-tips-bg.svg\",\"image_position\":\"top-right\",\"padding_bottom\":\"none\",\"padding_top\":\"xlarge\",\"style\":\"default\",\"title\":\"\u00bfcomo lo hacemos?\",\"title_breakpoint\":\"xl\",\"title_position\":\"center-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"large\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"headline\",\"props\":{\"animation\":\"parallax\",\"content\":\"Te interesa\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title_color\":\"primary\",\"title_element\":\"div\",\"title_style\":\"h4\"}},{\"type\":\"headline\",\"props\":{\"animation\":\"parallax\",\"content\":\"PLANIFICA TU VIAJE\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_top\":\"remove\",\"maxwidth\":\"xlarge\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title_element\":\"h2\",\"title_style\":\"heading-large\"}}]}]},{\"type\":\"row\",\"props\":{\"column_gap\":\"large\",\"layout\":\"1-2,1-2\",\"margin_bottom\":\"large\",\"margin_top\":\"large\",\"row_gap\":\"large\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"panel\",\"props\":{\"animation\":\"parallax\",\"content\":\"\n\n<p>Eres de los que te gusta compartir viajes, experiencias o vivencias. Este es tu viaje. Ir\u00e1s acompa\u00f1ado de gu\u00edas expertos en naturaleza y 4x4.<\/p>\n\n\\n\n\n<p>\u00a0<\/p>\n\n\",\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"large\",\"margin_top\":\"large\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title\":\"VIAJE GRUPAL\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_style\":\"h4\"}},{\"type\":\"panel\",\"props\":{\"animation\":\"parallax\",\"content\":\"\n\n<p>\u00a1Bienvenido igualmente! Organizamos <strong><a href=\\\"https:\/\/terranatur.es\/web\/cursos4x4\/\\\">cursos 4\u00d74<\/a><\/strong> de octubre a mayo donde te ense\u00f1aremos a sacar el m\u00e1ximo partido a tu m\u00e1quina, aprendiendo con seguridad y si da\u00f1ar tu coche. Adem\u00e1s, durante la expedici\u00f3n todoterreno aprender\u00e1s mucho mientras vas adquiriendo experiencia.\u00a0<\/p>\n\n\\n\n\n<p>En la parte de arriba est\u00e1 indicado el nivel del viaje.<\/p>\n\n\\n\n\n<p>Si tienes dudas de si esta expedici\u00f3n es para ti, <strong><a href=\\\"https:\/\/api.whatsapp.com\/send?phone=++34619324101&amp;text=Tengo%20dudas%20de%20si%20esta%20expedicion%20es%20para%20mi...\\\">contacta con nosotros.<\/a><\/strong><\/p>\n\n\\n\n\n\n\n\",\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"large\",\"margin_top\":\"large\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title\":\"NO TENGO EXPERIENCIA EN 4X4\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_style\":\"h4\"}},{\"type\":\"panel\",\"props\":{\"animation\":\"parallax\",\"content\":\"\n\n<p>En el precio del viaje por d\u00eda est\u00e1 inclu\u00edda la cena, desayuno y el alojamiento. Las comidas y los aperitivos (almuerzo), lo hacemos en campo con lo que cada cual trae, en ocasiones pararemos en lugares de carretera a comer.<\/p>\n\n\",\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"medium\",\"margin_top\":\"medium\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title\":\"COMIDAS \",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_style\":\"h4\"}},{\"type\":\"panel\",\"props\":{\"animation\":\"parallax\",\"content\":\"\n\n<p>Podemos ofrecerte un viaje autoguiado cuando quieras con tus amigos, grupos de varios coches o para vosotros solos. Tambi\u00e9n la posiblidad de contratar gu\u00eda en exclusiva para vuestro viaje. (Consulta).<\/p>\n\n\",\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"medium\",\"margin_top\":\"medium\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title\":\"\u00bfHay otras fechas? \u00bfPuedo ir por mi cuenta?\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_style\":\"h4\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"panel\",\"props\":{\"animation\":\"parallax\",\"content\":\"\n\n<p>Habr\u00e1 una reuni\u00f3n informativa y formativa online, sobre lo que debemos llevar a esta expedici\u00f3n, as\u00ed como para solucionar todas las dudas que se os presenten.<\/p>\n\n\",\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"medium\",\"margin_top\":\"medium\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title\":\"REUNI\u00d3N\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_style\":\"h4\"}},{\"type\":\"panel\",\"props\":{\"animation\":\"parallax\",\"content\":\"\n\n<p>No te preocupes. Es un viaje en el que puedes alquilar un Toyota Land Cruiser kdj 180 \\\"africano\\\".<\/p>\n\n\\n\n\n<p>Tambi\u00e9n en este viaje puedes venir de pasajero con conductor.\u00a0<\/p>\n\n\\n\n\n<p>Somos instructores todoterreno. Bienvenidos.<\/p>\n\n\",\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin_bottom\":\"medium\",\"margin_top\":\"medium\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"parallax_breakpoint\":\"m\",\"parallax_easing\":\"1\",\"parallax_y\":\"0,-200\",\"title\":\"NO TENGO 4X4\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\",\"title_style\":\"h4\"}},{\"type\":\"accordion\",\"props\":{\"collapsible\":true,\"content_column_breakpoint\":\"m\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"show_image\":true,\"show_link\":true},\"children\":[{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>La participaci\u00f3n en nuestras actividades de turismo 4x4 requiere el cumplimiento de las siguientes normas de seguridad, respeto medioambiental y conducta responsable:<\/p>\n\n\\n\n\n<h5>Condiciones Generales y Responsabilidad<\/h5>\n\n\\n\n\n<p>La conducci\u00f3n en veh\u00edculos 4x4 por terrenos naturales presenta riesgos inherentes, especialmente en condiciones adversas como pistas mojadas, embarradas o nevadas. <strong>Terranatur Naturaleza Activa<\/strong>\u00a0act\u00faa como organizadora de la actividad, pero no asume responsabilidad por accidentes derivados de una conducci\u00f3n inadecuada, fallos mec\u00e1nicos del veh\u00edculo o incumplimiento de las normas establecidas.\u00a0<strong>Al participar en esta actividad, asumes la responsabilidad de tu seguridad personal y la de terceros durante toda la ruta<\/strong>.<\/p>\n\n\\n\n\n<p>Para m\u00e1s informaci\u00f3n detallada sobre l\u00edmites de responsabilidad, seguros obligatorios y condiciones espec\u00edficas de participaci\u00f3n,\u00a0<strong>consulta nuestras <a href=\\\"https:\/\/terranatur.es\/web\/condiciones-generales\/\\\">Condiciones Generales<\/a> de Terranatur<\/strong>.<\/p>\n\n\\n\n\n<h5>Preparaci\u00f3n T\u00e9cnica del Veh\u00edculo<\/h5>\n\n\\n\n\n<p>Antes del inicio de la ruta aseg\u00farate que est\u00e1 bien mantenido y has reparado todo aquello que pueda dar problemas. Verifica el estado general de tu veh\u00edculo, especialmente neum\u00e1ticos, frenos, transmisiones y direcci\u00f3n. Mant\u00e9n siempre la\u00a0<strong>presi\u00f3n de neum\u00e1ticos adecuada<\/strong>\u00a0para el terreno a recorrer.<\/p>\n\n\\n\n\n<p>En pistas sin asfaltar, conduciremos siempre con la tracci\u00f3n integral (4x4).\u00a0<\/p>\n\n\\n\n\n<p><strong>Desconecta los sistemas electr\u00f3nicos de seguridad<\/strong>\u00a0de tu veh\u00edculo como ABS, ESP y control de estabilidad cuando sea t\u00e9cnicamente posible. Estos sistemas, dise\u00f1ados para carretera, pueden interferir negativamente en la conducci\u00f3n por terrenos irregulares y reducir la tracci\u00f3n efectiva.<\/p>\n\n\\n\n\n<h5>Normas de Conducci\u00f3n y Seguridad Vial<\/h5>\n\n\\n\n\n<h5>Velocidad y Distancias<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li><strong>Velocidad m\u00e1xima<\/strong>: 40 km\/h en pistas sin asfaltar, frecuentemente muy inferior seg\u00fan las condiciones del terreno.<\/li>\n\n\\n\n\n<li>En espacios protegidos y \u00e1reas reguladas: m\u00e1ximo\u00a0<strong>30 km\/h<\/strong><\/li>\n\n\\n\n\n<li>Mant\u00e9n una\u00a0<strong>distancia de seguridad prudencial<\/strong>\u00a0con el veh\u00edculo precedente.<\/li>\n\n\\n\n\n<li>Especialmente en las <strong>cuestas y en las bajadas pronunciadas<\/strong>, no inicies la maniobra hasta el compa\u00f1ero haya subido o bajado completamente ese tramo.<\/li>\n\n\\n\n\n<li>Circularemos en\u00a0<strong>grupos reducidos<\/strong>: m\u00e1ximo 3-5 veh\u00edculos.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>T\u00e9cnica de Conducci\u00f3n<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li>Adopta una\u00a0<strong>posici\u00f3n de conducci\u00f3n correcta<\/strong>: respaldo recto, brazos en \u00e1ngulo de 90\u00b0, volante sujetado con ambas manos en posici\u00f3n \\\"10 y 10\\\" con los pulgares fuera del aro.<\/li>\n\n\\n\n\n<li><strong>Cintur\u00f3n de seguridad abrochado<\/strong>\u00a0en todo momento.<\/li>\n\n\\n\n\n<li>Ojo: <strong>Nada de distracciones<\/strong>.<\/li>\n\n\\n\n\n<li>Aplica una\u00a0<strong>t\u00e9cnica de conducci\u00f3n suave<\/strong>: evita aceleraciones y frenadas bruscas.<\/li>\n\n\\n\n\n<li>En descensos pronunciados, utiliza el <strong>freno motor<\/strong> y mant\u00e9n el control constante del veh\u00edculo. Aprende a \\\"contravolantear\\\" si el veh\u00edculo derrapa.<\/li>\n\n\\n\n\n<li>Usa la <strong>reductora<\/strong> cuando veas que el terreno se complica, para salvar obst\u00e1culos, o para no forzar las tracciones en subidas o los frenos en bajadas.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>Respeto Medioambiental y Sostenibilidad\u00a0<\/h5>\n\n\\n\n\n<h5>Circulaci\u00f3n Responsable<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li><strong>Circula exclusivamente por pistas y caminos perfectamente delimitados<\/strong>. Est\u00e1 terminantemente prohibida la circulaci\u00f3n campo a trav\u00e9s.<\/li>\n\n\\n\n\n<li>Cuando te detengas, no bloquees la pista, pero evita pisar praderas o zonas con vegetaci\u00f3n.<\/li>\n\n\\n\n\n<li>No invadas propiedades privadas ni terrenos de cultivo<\/li>\n\n\\n\n\n<li>Respeta absolutamente la vegetaci\u00f3n existente:\u00a0<strong>no deteriores ni cortes vegetaci\u00f3n. <\/strong>\\\"Cada raya en la pintura cuenta una historia\\\" no lo olvides.<\/li>\n\n\\n\n\n<li><strong>Prohibido realizar trompos, derrapes o subir por laderas sin camino<\/strong> marcado.<\/li>\n\n\\n\n\n<li>Mejora tus destrezas, participando en nuestros <a href=\\\"https:\/\/terranatur.es\/web\/cursos4x4\/\\\"><strong>cursos 4x4 <\/strong><\/a>antes de ir de viaje.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>Protecci\u00f3n de la Fauna y Tranquilidad<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li><strong>Reduce la velocidad<\/strong>\u00a0significativamente al acercarte a personas y\/o animales. Detente si es necesario<\/li>\n\n\\n\n\n<li><strong>No utilices altavoces, claxon o sirenas<\/strong>, excepto por motivos estrictos de seguridad.<\/li>\n\n\\n\n\n<li><strong>Evita la m\u00fasica en las paradas.<\/strong> La mayor\u00eda de los otros participantes buscan la calma y el silencio en este tipo de rutas.<\/li>\n\n\\n\n\n<li>Mant\u00e9n el\u00a0<strong>dispositivo silenciador del escape<\/strong>\u00a0en perfecto estado.<\/li>\n\n\\n\n\n<li><strong>No pares nunca sobre hierba seca<\/strong>. Puede incendiarse tu veh\u00edculo.<\/li>\n\n\\n\n\n<li><strong>Evita producir ruidos<\/strong> injustificados que puedan perturbar la fauna silvestre.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>Gesti\u00f3n de Residuos<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li><strong>Prohibido arrojar cualquier objeto<\/strong>\u00a0al exterior del veh\u00edculo: latas, envases, colillas, etc.<\/li>\n\n\\n\n\n<li>Practica la filosof\u00eda Scout <strong>\\\"deja el lugar mejor de como lo encontraste\\\"<\/strong>: que no se note que hemos pasado por all\u00ed, incluso recoge lo que visualmente te moleste, aunque sea de otros.<\/li>\n\n\\n\n\n<li>Recoge todos tus residuos y depos\u00edtalos en lugares apropiados.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>Normas de Convivencia y Cortes\u00eda en el Monte<\/h5>\n\n\\n\n\n<h5>Prioridad y Respeto a Otros Usuarios\u00a0<\/h5>\n\n\\n\n\n<p><strong>Damos siempre prioridad absoluta al resto de usuarios del monte<\/strong>, deteni\u00e9ndonos completamente a su paso cuando sea necesario. Esto incluye especialmente a:<\/p>\n\n\\n\n\n<ul>\\n\n\n<li><strong>Senderistas<\/strong>\u00a0y monta\u00f1eros<\/li>\n\n\\n\n\n<li><strong>Ciclistas<\/strong>\u00a0de monta\u00f1a<\/li>\n\n\\n\n\n<li><strong>Jinetes<\/strong>\u00a0<strong>y amazonas<\/strong><\/li>\n\n\\n\n\n<li><strong>Motoristas<\/strong> de trial, trail o enduro<\/li>\n\n\\n\n\n<li><strong>Quads<\/strong>\u00a0y otros veh\u00edculos todo terreno<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>Protocolo de Cortes\u00eda<\/h5>\n\n\\n\n\n<p>Cuando te encuentres con otros usuarios del monte:<\/p>\n\n\\n\n\n<ol>\\n\n\n<li><strong>Avisa cort\u00e9smente cu\u00e1ntos veh\u00edculos vais a pasar<\/strong>: \\\"Buenos d\u00edas, somos 4 coches, vamos a pasar\\\"<\/li>\n\n\\n\n\n<li><strong>Saluda siempre con educaci\u00f3n y respeto<\/strong><\/li>\n\n\\n\n\n<li><strong>Inter\u00e9sate por su seguridad<\/strong>\u00a0cuando sea apropiado: \\\"\u00bfTodo bien? \u00bfNecesit\u00e1is ayuda?\\\"<\/li>\n\n\\n\n\n<li><strong>En caso de grupos grandes<\/strong>, pregunta si necesitan algo o si todo va bien<\/li>\n\n\\n\n\n<li><strong>Mant\u00e9n una actitud amigable<\/strong>\u00a0que represente los valores de Terranatur<\/li>\n\n\\n<\/ol>\n\n\\n\n\n<h5>Otras Normas de Convivencia.\u00a0<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li><strong>Cierra siempre todos los portillos ganaderos<\/strong>\u00a0tras el paso del grupo<\/li>\n\n\\n\n\n<li>Respeta las\u00a0<strong>se\u00f1ales de tr\u00e1fico y las indicaciones de agentes medioambientales<\/strong>.<\/li>\n\n\\n\n\n<li>En caso de encontrar <strong>ganado<\/strong> en el camino, reduce la velocidad al m\u00ednimo y espera pacientemente. Desde la ventanilla trata de animar a los animales a apartarse, dando palmadas en la chapa del coche o hablando en voz alta.\u00a0<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>Pol\u00edtica de Imagen y Derechos\u00a0<\/h5>\n\n\\n\n\n<p>Salvo indicaci\u00f3n expresa en contrario, tu participaci\u00f3n en la actividad implica la\u00a0<strong>autorizaci\u00f3n para el uso<\/strong>\u00a0de fotograf\u00edas y v\u00eddeos tomados durante la ruta.\u00a0<strong>Para conocer los detalles completos sobre el tratamiento de tu imagen y datos personales, consulta nuestra <a href=\\\"https:\/\/terranatur.es\/web\/privacidad\/\\\">pol\u00edtica de privacidad<\/a>.<\/strong>\u00a0Terranatur podr\u00e1 utilizarlas para:<\/p>\n\n\\n\n\n<ul>\\n\n\n<li>Facilitarte el acceso a las im\u00e1genes para tu uso personal.<\/li>\n\n\\n\n\n<li>Promoci\u00f3n y divulgaci\u00f3n de la empresa en Internet y redes sociales.<\/li>\n\n\\n\n\n<li>Material promocional y educativo sobre turismo responsable y conducci\u00f3n 4x4.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<h5>Compromiso con la Excelencia<\/h5>\n\n\\n\n\n<p>Tu experiencia es fundamental para nuestro crecimiento.\u00a0<strong>Agradecemos sinceramente tus comentarios y valoraciones<\/strong>\u00a0en Google, Facebook y otras plataformas. Tus opiniones nos ayudan a mejorar continuamente nuestros servicios y a ofrecer experiencias de mayor calidad a futuros participantes.<\/p>\n\n\\n\n\n<p><strong>Recuerda<\/strong>: El turismo 4x4 responsable es compatible con la conservaci\u00f3n del medio ambiente. Sigamos siendo\u00a0<strong>embajadores de la naturaleza<\/strong>\u00a0y demostremos que es posible disfrutar de la aventura respetando nuestro entorno natural.<\/p>\n\n\\n\n\n<p><strong>Terranatur Naturaleza Activa SLU<\/strong>\u00a0- Turismo de naturaleza sostenible y responsable.<\/p>\n\n\",\"title\":\"Normas y Recomendaciones de Seguridad\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<ul>\\n\n\n<li><strong>\u00a0<\/strong>Se puede consultar la informaci\u00f3n en materia administrativa y sanitaria en <a href=\\\"https:\/\/www.exteriores.gob.es\/es\/ServiciosAlCiudadano\/paginas\/detalle-recomendaciones-de-viaje.aspx?trc=marruecos\\\"> https:\/\/www.exteriores.gob.es\/es\/ServiciosAlCiudadano\/paginas\/detalle-recomendaciones-de-viaje.aspx?trc=marruecos<\/a>.<\/li>\n\n\\n\n\n<li>\\n\n\n<p>El viajero deber\u00e1 informar a Terranatur, con anterioridad a la contrataci\u00f3n, de aquellas solicitudes, peticiones o necesidades especiales que le fueren de aplicaci\u00f3n.<\/p>\n\n\\n<\/li>\n\n\\n\n\n<li>\\n\n\n<p>La informaci\u00f3n legal aplicable a la comercializaci\u00f3n del viaje combinado se encuentra a disposici\u00f3n de los consumidores en las <a href=\\\"https:\/\/terranatur.es\/web\/condiciones-generales\/\\\">condiciones generales<\/a><\/p>\n\n\\n<\/li>\n\n\\n\n\n<li>\\n\n\n<p>La conducci\u00f3n 4\u00d74 conlleva riesgos inherentes. Terranatur dispone de seguro de responsabilidad civil, pero<span>\u00a0<\/span><strong>no se responsabiliza de accidentes o da\u00f1os<\/strong><span>\u00a0<\/span>ocasionados por tu conducci\u00f3n o decisiones.<\/p>\n\n\\n<\/li>\n\n\\n\n\n<li>\\n\n\n<p>Debes llegar al alojamiento con el<span>\u00a0<\/span><strong>dep\u00f3sito lleno<\/strong>.\u00a0<\/p>\n\n\\n<\/li>\n\n\\n\n\n<li>\\n\n\n<p>Formar\u00e1s parte de un equipo de varios veh\u00edculos con puntos de reagrupamiento establecidos.<\/p>\n\n\\n<\/li>\n\n\\n\n\n<li>\\n\n\n<p>La organizaci\u00f3n podr\u00e1<span>\u00a0<\/span><strong>modificar el programa o alojamientos<\/strong><span>\u00a0<\/span>por motivos de log\u00edstica o inter\u00e9s del grupo.<\/p>\n\n\\n<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<p>Terranatur presta<span>\u00a0<\/span><strong>asistencia b\u00e1sica en ruta<\/strong>, pero ante cualquier rescate o actuaci\u00f3n de emergencia, la iniciativa debe partir del afectado, que colaborar\u00e1 como el que m\u00e1s.\u00a0<\/p>\n\n\\n\n\n<div class=\\\"el-h2\\\">\\n\n\n<h5 data-heading=\\\"Plazas y Organizaci\u00f3n\\\" dir=\\\"auto\\\">Plazas y Organizaci\u00f3n<\/h5>\n\n\\n\n\n<ul>\\n\n\n<li data-heading=\\\"Plazas y Organizaci\u00f3n\\\" dir=\\\"auto\\\"><span style=\\\"font-size: 16px;\\\">Las plazas son limitadas. El viaje est\u00e1 organizado por Terranatur Naturaleza Activa SLU (Agencia de Viajes CICMA 3161).<\/span><\/li>\n\n\\n<\/ul>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-h2\\\"><\/div>\n\n\\n\n\n<div class=\\\"el-h2\\\">\\n\n\n<h5 data-heading=\\\"Comunicaci\u00f3n y Navegaci\u00f3n\\\" dir=\\\"auto\\\"><span class=\\\"heading-collapse-indicator collapse-indicator collapse-icon\\\"><\/span>Comunicaci\u00f3n y Navegaci\u00f3n<\/h5>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-ul\\\">\\n\n\n<ul class=\\\"has-list-bullet\\\">\\n\n\n<li data-line=\\\"0\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span>Lleva tu<span>\u00a0<\/span><strong>emisora de 27 MHz<\/strong><span>\u00a0<\/span>para comunicarte con el grupo. Si no dispones de una, cons\u00faltanos: solemos llevar unidades a la venta.<\/li>\n\n\\n\n\n<li data-line=\\\"1\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span>Instala en tu m\u00f3vil una app de navegaci\u00f3n GPS (GAIA GPS, IGN Mapas, OruxMaps, GPX Viewer u otra similar) para seguir la ruta sin problemas.<\/li>\n\n\\n<\/ul>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-h2\\\">\\n\n\n<h5 data-heading=\\\"Provisiones y Equipamiento\\\" dir=\\\"auto\\\"><span class=\\\"heading-collapse-indicator collapse-indicator collapse-icon\\\"><\/span>Provisiones y Equipamiento<\/h5>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-ul\\\">\\n\n\n<ul class=\\\"has-list-bullet\\\">\\n\n\n<li data-line=\\\"0\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span>Trae<span>\u00a0<\/span><strong>almuerzo y comida<\/strong><span>\u00a0<\/span>para campo ambos d\u00edas; es habitual compartir lo que cada uno lleva.<\/li>\n\n\\n\n\n<li data-line=\\\"1\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span>Se recomiendan<span>\u00a0<\/span><strong>botas o zapatillas de trekking<\/strong>, prism\u00e1ticos y c\u00e1mara de fotos.<\/li>\n\n\\n<\/ul>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-h2\\\">\\n\n\n<h5 data-heading=\\\"Condiciones de Participaci\u00f3n\\\" dir=\\\"auto\\\"><span class=\\\"heading-collapse-indicator collapse-indicator collapse-icon\\\"><\/span>Condiciones de Participaci\u00f3n<\/h5>\n\n\\n<\/div>\n\n\\n\n\n<ul>\\n\n\n<li class=\\\"el-p\\\">Al participar aceptas estas normas y nuestras <strong><a href=\\\"https:\/\/terranatur.es\/web\/condiciones-generales\/\\\">condiciones Generales<\/a> de Terranatur<\/strong>, disponible en la web.<\/li>\n\n\\n<\/ul>\n\n\\n\n\n<div class=\\\"el-ol\\\">\\n\n\n<ul><\/ul>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-h2\\\">\\n\n\n<h5 data-heading=\\\"Pol\u00edtica de Cancelaciones y Reembolsos\\\" dir=\\\"auto\\\"><span class=\\\"heading-collapse-indicator collapse-indicator collapse-icon\\\"><\/span>Pol\u00edtica de Cancelaciones y Reembolsos<\/h5>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-ul\\\">\\n\n\n<ul class=\\\"has-list-bullet\\\">\\n\n\n<li data-line=\\\"0\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span>Se requiere un<span>\u00a0<\/span><strong>anticipo<\/strong><span>\u00a0<\/span>para reservar tu plaza.<\/li>\n\n\\n\n\n<li data-line=\\\"1\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span><strong>Cancelaciones 7 d\u00edas antes o menos<\/strong>: no hay devoluci\u00f3n del anticipo.<\/li>\n\n\\n\n\n<li data-line=\\\"2\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span>Si el alojamiento no reembolsa tu reserva, se te reclamar\u00e1 el importe \u00edntegro.<\/li>\n\n\\n\n\n<li data-line=\\\"3\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span><strong>Fuerza mayor acreditada<\/strong>: devoluci\u00f3n del 100% del importe.<\/li>\n\n\\n\n\n<li data-line=\\\"4\\\" dir=\\\"auto\\\"><span class=\\\"list-bullet\\\"><\/span>Cancelaciones por causas meteorol\u00f3gicas o imputables a la organizaci\u00f3n:<span>\u00a0<\/span><strong>reembolso \u00edntegro<\/strong>.<\/li>\n\n\\n<\/ul>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-p\\\">\\n\n\n<p dir=\\\"auto\\\">Consulta nuestras<span>\u00a0<\/span><a href=\\\"https:\/\/terranatur.es\/web\/condiciones-generales\/\\\"><strong>Condiciones Generales<\/strong><\/a><span>\u00a0<\/span>para los plazos concretos y otras informaciones esenciales.<\/p>\n\n\\n<\/div>\n\n\\n\n\n<div class=\\\"el-p\\\">\\n\n\n<p dir=\\\"auto\\\"><strong>Terranatur Naturaleza Activa SLU \u2013 CICMA 3161<\/strong><br \/>Tu aventura 4\u00d74, con total transparencia y compromiso.<\/p>\n\n\\n<\/div>\n\n\",\"title\":\"Avisos, organizaci\u00f3n y pol\u00edtica de cancelaci\u00f3n.\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><strong>En caso de aver\u00eda o accidente que impida continuar la ruta, sigue este protocolo:<\/strong><\/p>\n\n\\n\n\n<ol>\\n\n\n<li><strong> Parada Segura y Comunicaci\u00f3n<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>1.1 Det\u00e9n tu 4\u00d74 en un lugar seguro y activa las luces de emergencia.<\/p>\n\n\\n\n\n<p>1.2 Contacta al gu\u00eda o responsable de la ruta v\u00eda emisora de 27 MHz o tel\u00e9fono de la organizaci\u00f3n, indicando tu ubicaci\u00f3n y naturaleza del incidente.<\/p>\n\n\\n\n\n<ol start=\\\"2\\\">\\n\n\n<li><strong> Evaluaci\u00f3n de Riesgos y Espera de Instrucciones<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>2.1 Si existe riesgo de agravar la situaci\u00f3n (terreno inestable, gran inclinaci\u00f3n, vuelco fugas, etc.),\u00a0<strong>no intentes mover tu solo el veh\u00edculo<\/strong>.<\/p>\n\n\\n\n\n<p>2.2 Espera las\u00a0<strong>instrucciones expresas del organizador<\/strong>, que acudir\u00e1 de inmediato para evaluar y coordinar la intervenci\u00f3n.<\/p>\n\n\\n\n\n<ol start=\\\"3\\\">\\n\n\n<li><strong> Evacuaci\u00f3n de Ocupantes<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>3.1 Primero auxiliamos a los ocupantes para que abandonen el veh\u00edculo con total seguridad.<\/p>\n\n\\n\n\n<p>3.2 Al\u00e9jate de la calzada o pista, buscando refugio tras alg\u00fan elemento natural. Los pasajeros del coche afectado deber\u00e1n estar apartados de la zona de rescate para evitar posibles accidentes.<\/p>\n\n\\n\n\n<ol start=\\\"4\\\">\\n\n\n<li><strong> Rescate Inmediato por la Organizaci\u00f3n<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>4.1 La organizaci\u00f3n con tu colaboraci\u00f3n, intentar\u00e1 el\u00a0<strong>rescate y remolque del 4\u00d74<\/strong> antes de nada.<\/p>\n\n\\n\n\n<p>4.2 Sigue las indicaciones del gu\u00eda para el enganche, sujeci\u00f3n de eslingas o cabrestante y maniobras seguras. El rescate ser\u00e1 coordinado por el responsable de la ruta o quien este designe.<\/p>\n\n\\n\n\n<ol start=\\\"5\\\">\\n\n\n<li><strong> Llamada a Asistencia en Carretera<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>5.1 Si el rescate con los medios disponibles en ruta no es posible, o el veh\u00edculo no puede reemprender la marcha por aver\u00eda o da\u00f1os, el participante gestionar\u00e1 la llamada a la gr\u00faa o servicio de auxilio autorizado con la ayuda del gu\u00eda.<\/p>\n\n\\n\n\n<p>5.2 Facilita la ubicaci\u00f3n exacta y la descripci\u00f3n del problema.<\/p>\n\n\\n\n\n<ol start=\\\"6\\\">\\n\n\n<li><strong> Reincorporaci\u00f3n al Grupo<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>6.1 Te animaremos a que continues el viaje\u00a0<strong>subiendo como pasajero<\/strong> a un veh\u00edculo de la organizaci\u00f3n o al de otro participante que disponga de plazas libres.<\/p>\n\n\\n\n\n<p>6.2 Si decides\u00a0<strong>abandonar la ruta y regresar<\/strong>, esta decisi\u00f3n no da derecho a\u00a0<strong>devoluci\u00f3n<\/strong>\u00a0del coste de la actividad ni de servicios contratados.<\/p>\n\n\\n\n\n<ol start=\\\"7\\\">\\n\n\n<li><strong> Documentaci\u00f3n y Cierre de Incidente<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<p>7.1 Documenta el accidente mediante fotos, videos y una descripci\u00f3n escrita. Compromete a posibles testigos en caso de que sea necesaria una futura declaraci\u00f3n.<\/p>\n\n\\n\n\n<ol start=\\\"8\\\">\\n\n\n<li><strong> Recomendaciones Preventivas<\/strong><\/li>\n\n\\n<\/ol>\n\n\\n\n\n<ul>\\n\n\n<li>Revisa antes de la ruta frenos, transmisiones, niveles de l\u00edquidos y presi\u00f3n de neum\u00e1ticos.<\/li>\n\n\\n\n\n<li>Es obligatorio que cada veh\u00edculo venga con al menos dos anclajes de remolque bien sujetos al chasis; uno delantero y otro trasero.<\/li>\n\n\\n\n\n<li>Lleva\u00a0herramientas b\u00e1sicas, gato, fusibles, l\u00edquido anticongelante, aceite de motor, cinta americana, llave de arranque de repuesto, llave para quitar las tuercas (tambi\u00e9n las de seguridad), rueda de repuesto en buen estado y\u00a0botiqu\u00edn de primeros auxilios.<\/li>\n\n\\n\n\n<li>Agua, algo de comida y mantas.<\/li>\n\n\\n\n\n<li>Alguna herramienta de corte.<\/li>\n\n\\n\n\n<li>Mant\u00e9n siempre cargado el tel\u00e9fono m\u00f3vil.<\/li>\n\n\\n<\/ul>\n\n\",\"title\":\"Protocolo de Asistencia y Evacuaci\u00f3n por Aver\u00eda o Accidente\"}}]},{\"type\":\"button\",\"props\":{\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"RESERVAR AHORA\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"comprar\/reserva-dunas-raid-marruecos\/\"}}]}]}]}]},{\"name\":\"Hero\",\"type\":\"section\",\"props\":{\"height\":\"viewport\",\"height_viewport\":80,\"image\":\"wp-content\/uploads\/erg-marruecos.jpg\",\"image_effect\":\"parallax\",\"image_parallax_bgy\":\"-200,0\",\"image_parallax_breakpoint\":\"m\",\"image_parallax_easing\":\"1\",\"image_position\":\"top-center\",\"image_size\":\"cover\",\"image_width\":\"2560\",\"overlap\":true,\"padding_bottom\":\"large\",\"padding_top\":\"large\",\"style\":\"default\",\"text_color\":\"light\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"xsmall\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-1\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>.<\/p>\n\n\",\"margin_bottom\":\"remove\",\"margin_top\":\"remove\",\"maxwidth\":\"large\",\"text_color\":\"danger\",\"text_style\":\"lead\"}}]}]}]}],\"version\":\"5.0.15\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DUNAS RAID IX MARRUECOS. SEMANA SANTA 2026 Dos desiertos, un destino: Descubre Marruecos en 4&#215;4 Semana Santa: (26) 27 marzo &#8211; (5) 6 de abril de 2026 Riads, Kasbahs y Lodges con encanto y m\u00e1xima calidad hotelera en su zona. Gu\u00edas: Jaime Roset y Paloma Mill\u00e1n . \u00a1ALGUNAS PLAZAS LIBRES DE \u00daLTIMA HORA! Viajeros hasta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14550","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/pages\/14550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/comments?post=14550"}],"version-history":[{"count":77,"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/pages\/14550\/revisions"}],"predecessor-version":[{"id":15768,"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/pages\/14550\/revisions\/15768"}],"wp:attachment":[{"href":"https:\/\/terranatur.es\/web\/wp-json\/wp\/v2\/media?parent=14550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}